{"id":34694,"date":"2024-10-28T05:43:24","date_gmt":"2024-10-28T05:43:24","guid":{"rendered":"https:\/\/swiftlifts.com\/projects\/projects-townhouse-classia-khang-dien\/"},"modified":"2025-07-28T18:44:23","modified_gmt":"2025-07-28T18:44:23","slug":"projects-townhouse-classia-khang-dien","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/vn\/projects\/projects-townhouse-classia-khang-dien\/","title":{"rendered":"Projects &#8211; Townhouse Classia Khang Dien"},"content":{"rendered":"\n\t<section class=\"section why_a_home_lift\" id=\"section_259208790\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"633\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_hero_sw107255.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:90%\" id=\"row-495956243\">\n\n\t<div id=\"col-1849583031\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-453222206\" class=\"text\">\n\t\t\n<h1>Townhouse Classia Khang Dien<\/h1>\n\t\t\n<style>\n#text-453222206 {\n  font-size: 2rem;\n  color: rgb(255, 255, 255);\n}\n#text-453222206 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1849583031 > .col-inner {\n  margin: 200px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_259208790 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #dbe0d1;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_809018737\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-1767061949\">\n\n\t<div id=\"col-2038582747\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1448735064\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1448735064 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2038582747 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2038582747 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2127535194\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3670279676\" class=\"text\">\n\t\t\n<h2>Townhouse Classia Khang Dien<\/h2>\n\t\t\n<style>\n#text-3670279676 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-3670279676 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-294211080\" class=\"text\">\n\t\t\n<p>Ng\u01b0\u1eddi y\u00eau th\u00edch ki\u1ebfn tr\u00fac Ph\u00e1p T\u00e2n C\u1ed5 \u0110i\u1ec3n? V\u1eady th\u00ec, ch\u00e0o m\u1eebng b\u1ea1n \u0111\u1ebfn v\u1edbi c\u0103n nh\u00e0 ph\u1ed1 b\u1ed1n t\u1ea7ng n\u00e0y, \u0111\u01b0\u1ee3c trang b\u1ecb h\u1ec7 th\u1ed1ng SWIFT Pro ngay trong t\u1ea7m tay (ho\u1eb7c ch\u00e2n) t\u1ea1i qu\u1eadn Th\u1ee7 \u0110\u1ee9c s\u00f4i \u0111\u1ed9ng c\u1ee7a Th\u00e0nh ph\u1ed1 H\u1ed3 Ch\u00ed Minh, c\u00f2n \u0111\u01b0\u1ee3c bi\u1ebft \u0111\u1ebfn v\u1edbi t\u00ean g\u1ecdi S\u00e0i G\u00f2n.<\/p>\n<p>Ho\u00e0n th\u00e0nh v\u00e0o n\u0103m 2024, Classia Khang \u0110i\u1ec1n ho\u00e0n to\u00e0n m\u1edbi l\u00e0 m\u1ed9t ki\u1ec7t t\u00e1c hi\u1ec7n \u0111\u1ea1i v\u1edbi s\u1ef1 k\u1ebft h\u1ee3p v\u01b0\u1ee3t th\u1eddi gian gi\u1eefa c\u00e1c y\u1ebfu t\u1ed1 c\u1ed5 \u0111i\u1ec3n v\u00e0 \u0111\u01b0\u01a1ng \u0111\u1ea1i. C\u00e1c \u0111\u1eb7c \u0111i\u1ec3m ki\u1ebfn tr\u00fac c\u1ed5 \u0111i\u1ec3n nh\u01b0 c\u1ed9t Corinth, m\u00e1i v\u00f2m v\u00e0 c\u00e1c h\u1ecda ti\u1ebft trang tr\u00ed \u0111\u01b0\u1ee3c k\u1ebft h\u1ee3p tinh t\u1ebf v\u1edbi c\u00e1c ti\u1ec7n nghi hi\u1ec7n \u0111\u1ea1i nh\u01b0 k\u00ednh c\u01b0\u1eddng l\u1ef1c, th\u00e9p kh\u00f4ng g\u1ec9, h\u1ec7 th\u1ed1ng chi\u1ebfu s\u00e1ng th\u00f4ng minh v\u00e0 thang m\u00e1y gia \u0111\u00ecnh. N\u1ed9i th\u1ea5t c\u1ee7a nh\u00e0 ph\u1ed1 Classia Khang \u0110i\u1ec1n \u0111\u01b0\u1ee3c thi\u1ebft k\u1ebf t\u1ec9 m\u1ec9, k\u1ebft h\u1ee3p phong c\u00e1ch v\u00e0 ch\u1ea5t l\u01b0\u1ee3ng. C\u00e1c v\u1eadt li\u1ec7u cao c\u1ea5p nh\u01b0 g\u1ed7 t\u1ef1 nhi\u00ean, \u0111\u00e1 c\u1ea9m th\u1ea1ch v\u00e0 kim lo\u1ea1i h\u00f2a quy\u1ec7n t\u1ea1o n\u00ean kh\u00f4ng gian v\u1eeba \u1ea5m c\u00fang v\u1eeba sang tr\u1ecdng. S\u1ef1 h\u00e0i h\u00f2a ho\u00e0n h\u1ea3o gi\u1eefa m\u00e0u s\u1eafc v\u00e0 \u00e1nh s\u00e1ng t\u1ef1 nhi\u00ean mang \u0111\u1ebfn m\u1ed9t b\u1ea7u kh\u00f4ng kh\u00ed th\u01b0 th\u00e1i v\u00e0 tinh t\u1ebf cho c\u1ea3 gia \u0111\u00ecnh, v\u1edbi thi\u00ean nhi\u00ean ngay c\u1ea1nh nh\u00e0<\/p>\n<p><b>Model:<\/b> SWIFT Pro<br \/>\n<b>Floors:<\/b> 4<br \/>\n<b>Lift Size: <\/b>Small, S (830&#215;1000 mm)<br \/>\n<b>Lift Colour:<\/b> Traffic White<br \/>\n<b>ArtWall:<\/b> INK Bronze<br \/>\n<b>Lift Carpet:<\/b> Linen Grey<br \/>\n<b>Location:<\/b> Th\u1ee7 \u0110\u1ee9c district, Ho Chi Minh City aka Saigon<\/p>\n\t\t\n<style>\n#text-294211080 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-294211080 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-right\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;background-color:rgb(255, 145, 150);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2127535194 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2127535194 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_809018737 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_729400435\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1162200269\">\n\n\t<div id=\"col-638912557\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1934916041\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1934916041 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1572056324\" class=\"text\">\n\t\t\n<p>SWIFT Pro v\u1edbi m\u00e0u tr\u1eafng Traffic White, k\u1ebft h\u1ee3p c\u00f9ng th\u1ea3m Linen Grey v\u00e0 t\u01b0\u1eddng ngh\u1ec7 thu\u1eadt ArtWall INK Bronze, t\u1ea1o n\u00ean s\u1ef1 h\u00e0i h\u00f2a tuy\u1ec7t \u0111\u1eb9p cho kh\u00f4ng gian n\u1ed9i th\u1ea5t s\u00e1ng m\u00e0u v\u1edbi g\u1ed7 v\u00e0 \u0111\u00e1 c\u1ea9m th\u1ea1ch. V\u1eeba thanh l\u1ecbch v\u1eeba h\u00e0i h\u00f2a.<\/p>\n\t\t\n<style>\n#text-1572056324 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1572056324 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-638912557 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-638912557 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_729400435 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_851392600\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-834734464\">\n\n\t<div id=\"col-480220084\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_681758803\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"405\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12-768x405.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12.jpg 2000w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_681758803 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1460737801\" class=\"text\">\n\t\t\n<div class=\"flex max-w-full flex-col flex-grow\">\n<div class=\"min-h-8 text-message flex w-full flex-col items-end gap-2 whitespace-normal break-words &#091;.text-message+&amp;&#093;:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"46f7d251-00d2-4d49-b959-e383a62da8a4\" data-message-model-slug=\"gpt-4o\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-&#091;3px&#093;\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>C\u00e1c t\u00f4ng m\u00e0u be kh\u00e1c nhau t\u1ea1o c\u1ea3m gi\u00e1c y\u00ean b\u00ecnh trong nh\u00e0 ph\u1ed1 Classia Khang \u0110i\u1ec1n.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\n<style>\n#text-1460737801 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1460737801 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-480220084 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-480220084 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_851392600 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_351978760\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-553198921\">\n\n\t<div id=\"col-1068357771\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1003453950\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1003453950 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-630631464\" class=\"text\">\n\t\t\n<p>Song h\u00e0nh c\u00f9ng nhau. B\u00ean ngo\u00e0i, m\u1eb7t ti\u1ec1n phong c\u00e1ch Ph\u00e1p T\u00e2n C\u1ed5 \u0110i\u1ec3n, \u0111\u01b0\u1ee3c t\u00f4 \u0111i\u1ec3m b\u1eb1ng c\u00e1c c\u1ed9t Corinth v\u00e0 nh\u1eefng chi ti\u1ebft tuy\u1ec7t \u0111\u1eb9p, th\u1ec3 hi\u1ec7n s\u1ef1 thanh l\u1ecbch v\u00e0 tinh t\u1ebf v\u01b0\u1ee3t th\u1eddi gian.<\/p>\n\t\t\n<style>\n#text-630631464 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-630631464 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1068357771 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1068357771 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1950284192\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_84444800\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_84444800 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2405284459\" class=\"text\">\n\t\t\n<p>B\u00ean trong l\u00e0 m\u1ed9t \u1ed1c \u0111\u1ea3o hi\u1ec7n \u0111\u1ea1i: c\u00e1c y\u1ebfu t\u1ed1 hi\u1ec7n \u0111\u1ea1i nh\u01b0 k\u00ednh c\u01b0\u1eddng l\u1ef1c v\u00e0 h\u1ec7 th\u1ed1ng chi\u1ebfu s\u00e1ng th\u00f4ng minh h\u00f2a quy\u1ec7n ho\u00e0n h\u1ea3o v\u1edbi ti\u1ec7n nghi c\u1ee7a thang m\u00e1y gia \u0111\u00ecnh ri\u00eang.<\/p>\n\t\t\n<style>\n#text-2405284459 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-2405284459 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1950284192 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1950284192 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_351978760 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1367666071\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1355217831\">\n\n\t<div id=\"col-669211111\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_582669153\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_582669153 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3100697396\" class=\"text\">\n\t\t\n<p>T\u1ea5t c\u1ea3 n\u1eb1m \u1edf nh\u1eefng chi ti\u1ebft.<\/p>\n\t\t\n<style>\n#text-3100697396 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-3100697396 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-669211111 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-669211111 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-377090402\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_432299321\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_432299321 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1835890748\" class=\"text\">\n\t\t\n<p>S\u1ef1 h\u00e0i h\u00f2a ho\u00e0n h\u1ea3o: th\u1ea3m SWIFT Pro v\u00e0 s\u00e0n \u0111\u00e1 c\u1ea9m th\u1ea1ch chia s\u1ebb m\u1ed9t b\u1ea3ng m\u00e0u tuy\u1ec7t \u0111\u1eb9p.<\/p>\n\t\t\n<style>\n#text-1835890748 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-1835890748 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-377090402 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-377090402 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1367666071 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1938561670\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-2034021758\">\n\n\t<div id=\"col-1258561220\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1837942814\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1837942814 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1274864864\" class=\"text\">\n\t\t\n<p>Classia Kheng Dien Townhouse &#8211; S\u1ef1 k\u1ebft h\u1ee3p v\u01b0\u1ee3t th\u1eddi gian gi\u1eefa c\u00e1c y\u1ebfu t\u1ed1 c\u1ed5 \u0111i\u1ec3n v\u00e0 hi\u1ec7n \u0111\u1ea1i.<\/p>\n\t\t\n<style>\n#text-1274864864 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1274864864 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1258561220 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1258561220 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1938561670 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_303730989\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-29861740\">\n\n\t<div id=\"col-847601627\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_829695380\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"405\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14-768x405.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14.jpg 2000w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_829695380 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2550650611\" class=\"text\">\n\t\t\n<p>Nh\u00e0 ph\u1ed1 \u0111\u01b0\u1ee3c bao ph\u1ee7 b\u1edfi t\u00f4ng m\u00e0u tr\u1eafng v\u00e0 c\u00e1c gam m\u00e0u \u0111\u1ea5t, l\u00e0m n\u1ed5i b\u1eadt th\u00eam s\u1ef1 \u0111\u1eb7c bi\u1ec7t khi b\u1ea1n c\u00f3 th\u1ec3 thay \u0111\u1ed5i m\u00e0u s\u1eafc v\u00e0 c\u01b0\u1eddng \u0111\u1ed9 \u00e1nh s\u00e1ng c\u1ee7a tr\u1ee5c SWIFT Pro ch\u1ec9 b\u1eb1ng m\u1ed9t ch\u1ea1m \u0111\u01a1n gi\u1ea3n.<\/p>\n\t\t\n<style>\n#text-2550650611 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2550650611 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-847601627 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-847601627 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_303730989 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_842481927\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-432799180\">\n\n\t<div id=\"col-1171872829\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_171603177\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_171603177 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-911304524\" class=\"text\">\n\t\t\n<p>M\u00e0u RGB c\u1ee7a SWIFT Pro c\u00f3 \u0111\u1ee7 m\u1ecdi s\u1eafc th\u00e1i c\u1ee7a c\u1ea7u v\u1ed3ng. Trong h\u00ecnh l\u00e0 m\u00e0u Xanh B\u0103ng Gi\u00e1 (Frozen Blue).<\/p>\n\t\t\n<style>\n#text-911304524 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-911304524 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1171872829 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1171872829 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_842481927 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1247158826\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1776877971\">\n\n\t<div id=\"col-1791205779\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/projects\/\" class=\"button alert lowercase\" >\n\t\t<span>Click here to see more projects<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1791205779 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1791205779 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-742557812\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-pro-residential-lift\/\" class=\"button primary lowercase\" >\n\t\t<span>SWIFT Pro product page<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-742557812 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-742557812 > .col-inner {\n    padding: 0px 30% 0px 0%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1247158826 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":34667,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-34694","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u1ef1 \u00e1n - Nh\u00e0 ph\u1ed1 Classia Khang \u0110i\u1ec1n - SWIFT Lifts<\/title>\n<meta name=\"description\" content=\"Classia Khang \u0110i\u1ec1n t\u00edch h\u1ee3p thang m\u00e1y SWIFT Pro trong thi\u1ebft k\u1ebf Ph\u00e1p sang tr\u1ecdng, n\u00e2ng t\u1ea7m kh\u00f4ng gian s\u1ed1ng t\u1ea1i TP. H\u1ed3 Ch\u00ed Minh.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/vn\/projects\/projects-townhouse-classia-khang-dien\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - Townhouse Classia Khang Dien\" \/>\n<meta property=\"og:description\" content=\"Classia Khang \u0110i\u1ec1n t\u00edch h\u1ee3p thang m\u00e1y SWIFT Pro trong thi\u1ebft k\u1ebf Ph\u00e1p sang tr\u1ecdng, n\u00e2ng t\u1ea7m kh\u00f4ng gian s\u1ed1ng t\u1ea1i TP. H\u1ed3 Ch\u00ed Minh.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/vn\/projects\/projects-townhouse-classia-khang-dien\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T18:44:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/projects\\\/projects-townhouse-classia-khang-dien\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/projects\\\/projects-townhouse-classia-khang-dien\\\/\",\"name\":\"D\u1ef1 \u00e1n - Nh\u00e0 ph\u1ed1 Classia Khang \u0110i\u1ec1n - SWIFT Lifts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/#website\"},\"datePublished\":\"2024-10-28T05:43:24+00:00\",\"dateModified\":\"2025-07-28T18:44:23+00:00\",\"description\":\"Classia Khang \u0110i\u1ec1n t\u00edch h\u1ee3p thang m\u00e1y SWIFT Pro trong thi\u1ebft k\u1ebf Ph\u00e1p sang tr\u1ecdng, n\u00e2ng t\u1ea7m kh\u00f4ng gian s\u1ed1ng t\u1ea1i TP. H\u1ed3 Ch\u00ed Minh.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/projects\\\/projects-townhouse-classia-khang-dien\\\/#breadcrumb\"},\"inLanguage\":\"vn-VN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/projects\\\/projects-townhouse-classia-khang-dien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/projects\\\/projects-townhouse-classia-khang-dien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projects &#8211; Townhouse Classia Khang Dien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"vn-VN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"vn-VN\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/vn\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u1ef1 \u00e1n - Nh\u00e0 ph\u1ed1 Classia Khang \u0110i\u1ec1n - SWIFT Lifts","description":"Classia Khang \u0110i\u1ec1n t\u00edch h\u1ee3p thang m\u00e1y SWIFT Pro trong thi\u1ebft k\u1ebf Ph\u00e1p sang tr\u1ecdng, n\u00e2ng t\u1ea7m kh\u00f4ng gian s\u1ed1ng t\u1ea1i TP. H\u1ed3 Ch\u00ed Minh.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/vn\/projects\/projects-townhouse-classia-khang-dien\/","og_locale":"en_US","og_type":"article","og_title":"Projects - Townhouse Classia Khang Dien","og_description":"Classia Khang \u0110i\u1ec1n t\u00edch h\u1ee3p thang m\u00e1y SWIFT Pro trong thi\u1ebft k\u1ebf Ph\u00e1p sang tr\u1ecdng, n\u00e2ng t\u1ea7m kh\u00f4ng gian s\u1ed1ng t\u1ea1i TP. H\u1ed3 Ch\u00ed Minh.","og_url":"https:\/\/swiftlifts.com\/vn\/projects\/projects-townhouse-classia-khang-dien\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","article_modified_time":"2025-07-28T18:44:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/vn\/projects\/projects-townhouse-classia-khang-dien\/","url":"https:\/\/swiftlifts.com\/vn\/projects\/projects-townhouse-classia-khang-dien\/","name":"D\u1ef1 \u00e1n - Nh\u00e0 ph\u1ed1 Classia Khang \u0110i\u1ec1n - SWIFT Lifts","isPartOf":{"@id":"https:\/\/swiftlifts.com\/vn\/#website"},"datePublished":"2024-10-28T05:43:24+00:00","dateModified":"2025-07-28T18:44:23+00:00","description":"Classia Khang \u0110i\u1ec1n t\u00edch h\u1ee3p thang m\u00e1y SWIFT Pro trong thi\u1ebft k\u1ebf Ph\u00e1p sang tr\u1ecdng, n\u00e2ng t\u1ea7m kh\u00f4ng gian s\u1ed1ng t\u1ea1i TP. H\u1ed3 Ch\u00ed Minh.","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/vn\/projects\/projects-townhouse-classia-khang-dien\/#breadcrumb"},"inLanguage":"vn-VN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/vn\/projects\/projects-townhouse-classia-khang-dien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/vn\/projects\/projects-townhouse-classia-khang-dien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/vn\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/swiftlifts.com\/vn\/projects\/"},{"@type":"ListItem","position":3,"name":"Projects &#8211; Townhouse Classia Khang Dien"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/vn\/#website","url":"https:\/\/swiftlifts.com\/vn\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/vn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/vn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"vn-VN"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/vn\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/vn\/","logo":{"@type":"ImageObject","inLanguage":"vn-VN","@id":"https:\/\/swiftlifts.com\/vn\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/vn\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/vn\/wp-json\/wp\/v2\/pages\/34694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/vn\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/vn\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/vn\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/vn\/wp-json\/wp\/v2\/comments?post=34694"}],"version-history":[{"count":5,"href":"https:\/\/swiftlifts.com\/vn\/wp-json\/wp\/v2\/pages\/34694\/revisions"}],"predecessor-version":[{"id":38880,"href":"https:\/\/swiftlifts.com\/vn\/wp-json\/wp\/v2\/pages\/34694\/revisions\/38880"}],"up":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/vn\/wp-json\/wp\/v2\/pages\/34667"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/vn\/wp-json\/wp\/v2\/media?parent=34694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}