{"id":26022,"date":"2023-11-10T13:14:01","date_gmt":"2023-11-10T13:14:01","guid":{"rendered":"https:\/\/swiftlifts.com\/district-5-detached-villa\/"},"modified":"2026-03-26T13:09:55","modified_gmt":"2026-03-26T13:09:55","slug":"district-5-detached-villa","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/ph\/projects\/district-5-detached-villa\/","title":{"rendered":"Projects &#8211; District 5 Detached Villa"},"content":{"rendered":"\n\t<section class=\"section why_a_home_lift\" id=\"section_270014149\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"633\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_hero_Ho-chi-mihn.jpg\" class=\"bg attachment- size-\" alt=\"project hero Ho chi mihn\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:90%\" id=\"row-455888983\">\n\n\t<div id=\"col-120773230\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-557056839\" class=\"text\">\n\t\t\n<h1>District 5 Detached Villa<\/h1>\n\t\t\n<style>\n#text-557056839 {\n  font-size: 2rem;\n  color: rgb(255, 255, 255);\n}\n#text-557056839 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-120773230 > .col-inner {\n  margin: 200px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_270014149 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #dbe0d1;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_2076999085\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-756501925\">\n\n\t<div id=\"col-1627480159\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_343899886\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_01-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_01-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_01-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_01-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_01-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_01.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_343899886 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1627480159 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1627480159 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1874255578\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3943936284\" class=\"text\">\n\t\t\n<h2>District 5 Detached Villa<\/h2>\n\t\t\n<style>\n#text-3943936284 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-3943936284 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1249538829\" class=\"text\">\n\t\t\n<p>This Vietnamese classic home takes inspiration from Roman villas, showcasing wood and marble interiors. A recent upgrade included a forward-looking decision to add a SWIFT Pro. The villa features warm colours that match beautifully with\u00a0 SWIFT Pro and the ArtWall INK adorned in gold and bronze accents.<\/p>\n<p><b>Model:<\/b> SWIFT Pro<br \/>\n<b>Floors:<\/b> 2<br \/>\n<b>Lift Size: <\/b>M<br \/>\n<b>Lift Colour:<\/b> Traffic White<br \/>\n<b>ArtWall:<\/b> INK Bronze<br \/>\n<b>Lift Carpet:<\/b> Denim Stripe<br \/>\n<b>Location:<\/b> District 5 &#8211; at the heart of Chinatown of Ho Chi Minh City, Vietnam<\/p>\n\t\t\n<style>\n#text-1249538829 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1249538829 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-right\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;background-color:rgb(255, 145, 150);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1874255578 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1874255578 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2076999085 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1797374112\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1955050943\">\n\n\t<div id=\"col-1158728575\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1709392964\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_09-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_09-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_09-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_09-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_09-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_09.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1709392964 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-788057455\" class=\"text\">\n\t\t\n<p>This classic home takes inspiration from Roman villas showcasing wood and marble interiors.<\/p>\n\t\t\n<style>\n#text-788057455 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-788057455 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1158728575 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1158728575 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1797374112 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1628562245\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1948824401\">\n\n\t<div id=\"col-88495943\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_811567501\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_05-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_05-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_05-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_05-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_05-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_05.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_811567501 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-4239037535\" class=\"text\">\n\t\t\n<p>Villa District 5 is characterised by an interior dominated by warm colours.<\/p>\n\t\t\n<style>\n#text-4239037535 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-4239037535 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-88495943 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-88495943 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1915956869\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_508641539\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_03-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_03-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_03-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_03-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_03-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_03.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_508641539 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1314761733\" class=\"text\">\n\t\t\n<p>A symphony of elements merging seamlessly with the inviting interior palette.<\/p>\n\t\t\n<style>\n#text-1314761733 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-1314761733 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1915956869 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1915956869 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1628562245 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_123516855\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-959529712\">\n\n\t<div id=\"col-295584040\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1284881534\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_08-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_08-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_08-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_08-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_08-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape-ho-chi-minh_08.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1284881534 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3656243889\" class=\"text\">\n\t\t\n<p>SWIFT Pro also serves as an additional light source, customizable to suit mood or weather.<\/p>\n\t\t\n<style>\n#text-3656243889 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-3656243889 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-295584040 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-295584040 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_123516855 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_457064273\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1319931894\">\n\n\t<div id=\"col-1741999197\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_458952032\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_04-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_04-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_04-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_04-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_04-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_04.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_458952032 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-713336557\" class=\"text\">\n\t\t\n<p>A recent upgrade included a forward-looking decision to add a SWIFT Pro home lift<\/p>\n\t\t\n<style>\n#text-713336557 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-713336557 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1741999197 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1741999197 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-481683379\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_230157512\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_06-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_06-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_06-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_06-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_06-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait-ho-chi-minh_06.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_230157512 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1952772018\" class=\"text\">\n\t\t\n<p>SWIFT Pro adorned with Ege Carpet in Denim Stripe and harmonized by ArtWall Ink.<\/p>\n\t\t\n<style>\n#text-1952772018 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-1952772018 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-481683379 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-481683379 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-438905920\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/projects\/\" class=\"button alert lowercase\" >\n\t\t<span>Click here to see more projects<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-438905920 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-438905920 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-415951297\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-pro-residential-lift\/\" class=\"button primary lowercase\" >\n\t\t<span>SWIFT Pro product page<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-415951297 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-415951297 > .col-inner {\n    padding: 0px 30% 0px 0%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_457064273 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"parent":26034,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-26022","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Project \u2013 District\u202f5 Detached Villa | Swift<\/title>\n<meta name=\"description\" content=\"Explore a District 5 villa featuring a stylish SWIFT home lift, enhancing comfort, accessibility, and modern multi-level living.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/ph\/projects\/district-5-detached-villa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - District 5 Detached Villa\" \/>\n<meta property=\"og:description\" content=\"Explore a District 5 villa featuring a stylish SWIFT home lift, enhancing comfort, accessibility, and modern multi-level living.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/ph\/projects\/district-5-detached-villa\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T13:09:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/projects\\\/district-5-detached-villa\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/projects\\\/district-5-detached-villa\\\/\",\"name\":\"Project \u2013 District\u202f5 Detached Villa | Swift\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/#website\"},\"datePublished\":\"2023-11-10T13:14:01+00:00\",\"dateModified\":\"2026-03-26T13:09:55+00:00\",\"description\":\"Explore a District 5 villa featuring a stylish SWIFT home lift, enhancing comfort, accessibility, and modern multi-level living.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/projects\\\/district-5-detached-villa\\\/#breadcrumb\"},\"inLanguage\":\"ph-EN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/projects\\\/district-5-detached-villa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/projects\\\/district-5-detached-villa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projects &#8211; District 5 Detached Villa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ph-EN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ph-EN\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/ph\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Project \u2013 District\u202f5 Detached Villa | Swift","description":"Explore a District 5 villa featuring a stylish SWIFT home lift, enhancing comfort, accessibility, and modern multi-level living.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/ph\/projects\/district-5-detached-villa\/","og_locale":"en_US","og_type":"article","og_title":"Projects - District 5 Detached Villa","og_description":"Explore a District 5 villa featuring a stylish SWIFT home lift, enhancing comfort, accessibility, and modern multi-level living.","og_url":"https:\/\/swiftlifts.com\/ph\/projects\/district-5-detached-villa\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","article_modified_time":"2026-03-26T13:09:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/ph\/projects\/district-5-detached-villa\/","url":"https:\/\/swiftlifts.com\/ph\/projects\/district-5-detached-villa\/","name":"Project \u2013 District\u202f5 Detached Villa | Swift","isPartOf":{"@id":"https:\/\/swiftlifts.com\/ph\/#website"},"datePublished":"2023-11-10T13:14:01+00:00","dateModified":"2026-03-26T13:09:55+00:00","description":"Explore a District 5 villa featuring a stylish SWIFT home lift, enhancing comfort, accessibility, and modern multi-level living.","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/ph\/projects\/district-5-detached-villa\/#breadcrumb"},"inLanguage":"ph-EN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/ph\/projects\/district-5-detached-villa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/ph\/projects\/district-5-detached-villa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/ph\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/swiftlifts.com\/ph\/projects\/"},{"@type":"ListItem","position":3,"name":"Projects &#8211; District 5 Detached Villa"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/ph\/#website","url":"https:\/\/swiftlifts.com\/ph\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/ph\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/ph\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ph-EN"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/ph\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/ph\/","logo":{"@type":"ImageObject","inLanguage":"ph-EN","@id":"https:\/\/swiftlifts.com\/ph\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/ph\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/ph\/wp-json\/wp\/v2\/pages\/26022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/ph\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/ph\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/ph\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/ph\/wp-json\/wp\/v2\/comments?post=26022"}],"version-history":[{"count":2,"href":"https:\/\/swiftlifts.com\/ph\/wp-json\/wp\/v2\/pages\/26022\/revisions"}],"predecessor-version":[{"id":59820,"href":"https:\/\/swiftlifts.com\/ph\/wp-json\/wp\/v2\/pages\/26022\/revisions\/59820"}],"up":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/ph\/wp-json\/wp\/v2\/pages\/26034"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/ph\/wp-json\/wp\/v2\/media?parent=26022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}