{"id":45556,"date":"2023-11-10T10:47:01","date_gmt":"2023-11-10T10:47:01","guid":{"rendered":"https:\/\/swiftlifts.com\/villa-al-hamra\/"},"modified":"2026-03-09T14:04:45","modified_gmt":"2026-03-09T14:04:45","slug":"villa-al-hamra","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/no\/projects\/villa-al-hamra\/","title":{"rendered":"Projects &#8211; Villa Al Hamra"},"content":{"rendered":"\n\t<section class=\"section why_a_home_lift\" id=\"section_242701056\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"633\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_hero_al-hamra.jpg\" class=\"bg attachment- size-\" alt=\"project hero al hamra\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:90%\" id=\"row-441275085\">\n\n\t<div id=\"col-2033517102\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1042624246\" class=\"text\">\n\t\t\n<h1>Villa Al Hamra<\/h1>\n\t\t\n<style>\n#text-1042624246 {\n  font-size: 2rem;\n  color: rgb(255, 255, 255);\n}\n#text-1042624246 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2033517102 > .col-inner {\n  margin: 200px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_242701056 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #dbe0d1;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_851551343\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-870257612\">\n\n\t<div id=\"col-1918918091\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1870214209\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_01-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_01-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_01-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_01-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_01-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_01.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1870214209 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1918918091 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1918918091 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1839177289\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3301631360\" class=\"text\">\n\t\t\n<h2>Villa Al Hamra<\/h2>\n\t\t\n<style>\n#text-3301631360 {\n  font-size: 1rem;\n  color: rgb(30, 98, 122);\n}\n#text-3301631360 > * {\n  color: rgb(30, 98, 122);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2168417500\" class=\"text\">\n\t\t\n<p>&#8211; a two-storey villa with a SWIFT as the center piece. A home in classic Arabic style, marble flooring and a big garden with swimming pool.<\/p>\n<p><b>Model:<\/b> SWIFT Lite<br \/>\n<b>Floors:<\/b> 2<br \/>\n<b>Lift Size: <\/b>M<br \/>\n<b>Lift Colour:<\/b> Traffic White<br \/>\n<b>ArtWall:<\/b> Resin Board<br \/>\n<b>Lift Carpet:<\/b> Una Micro Grey<br \/>\n<b>Location:<\/b> North part of Riyadh, Saudi Arabia<\/p>\n\t\t\n<style>\n#text-2168417500 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-2168417500 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-right\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;background-color:rgb(131, 175, 175);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1839177289 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1839177289 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_851551343 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1472929565\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-585116302\">\n\n\t<div id=\"col-162665090\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_477070137\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_02-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_02-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_02-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_02-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_02-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_02.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_477070137 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1620255006\" class=\"text\">\n\t\t\n<p>A glimpse of SWIFT Lite from the ground floor of Villa Hamra.<\/p>\n\t\t\n<style>\n#text-1620255006 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-1620255006 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-162665090 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-162665090 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1838844679\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1178572614\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_04-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_04-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_04-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_04-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_04-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_portrait_al-hamra_04.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1178572614 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1456357128\" class=\"text\">\n\t\t\n<p>Big garden with palm trees.<\/p>\n\t\t\n<style>\n#text-1456357128 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-1456357128 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1838844679 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1838844679 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1472929565 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_807035573\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1307680794\">\n\n\t<div id=\"col-1573739972\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_847660252\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_06-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_06-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_06-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_06-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_06-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_06.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_847660252 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2344049389\" class=\"text\">\n\t\t\n<p>Black and white is always a good idea.<\/p>\n\t\t\n<style>\n#text-2344049389 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-2344049389 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1573739972 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1573739972 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_807035573 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1505928687\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-25492024\">\n\n\t<div id=\"col-103060863\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1842670875\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_05-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_05-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_05-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_05-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_05-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_05.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1842670875 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-917389718\" class=\"text\">\n\t\t\n<p>SWIFT Lite connects floors with bedrooms and social spaces.<\/p>\n\t\t\n<style>\n#text-917389718 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-917389718 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-103060863 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-103060863 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1505928687 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1973101501\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1307053083\">\n\n\t<div id=\"col-595386904\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_157831911\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_07-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_07-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_07-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_07-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_07-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/11\/project_landscape_al-hamra_07.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_157831911 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3710733924\" class=\"text\">\n\t\t\n<p>Street view of Villa Al Hamra.<\/p>\n\t\t\n<style>\n#text-3710733924 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-3710733924 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-595386904 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-595386904 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1170713741\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/projects\/\" class=\"button alert lowercase\" >\n\t\t<span>Click here to see more projects<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1170713741 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1170713741 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1222382654\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-lite-a-small-house-lift\/\" class=\"button success lowercase\" >\n\t\t<span>SWIFT Lite product page<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1222382654 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1222382654 > .col-inner {\n    padding: 0px 30% 0px 0%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1973101501 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":45564,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-45556","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Projects - Villa Al Hamra - SWIFT - 100% battery driven home lifts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/no\/projects\/villa-al-hamra\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - Villa Al Hamra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/no\/projects\/villa-al-hamra\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T14:04:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Ansl. lesetid\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/projects\\\/villa-al-hamra\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/projects\\\/villa-al-hamra\\\/\",\"name\":\"Projects - Villa Al Hamra - SWIFT - 100% battery driven home lifts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/#website\"},\"datePublished\":\"2023-11-10T10:47:01+00:00\",\"dateModified\":\"2026-03-09T14:04:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/projects\\\/villa-al-hamra\\\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/no\\\/projects\\\/villa-al-hamra\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/projects\\\/villa-al-hamra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projects &#8211; Villa Al Hamra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/no\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Projects - Villa Al Hamra - SWIFT - 100% battery driven home lifts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/no\/projects\/villa-al-hamra\/","og_locale":"nb_NO","og_type":"article","og_title":"Projects - Villa Al Hamra","og_url":"https:\/\/swiftlifts.com\/no\/projects\/villa-al-hamra\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","article_modified_time":"2026-03-09T14:04:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Ansl. lesetid":"2 minutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/no\/projects\/villa-al-hamra\/","url":"https:\/\/swiftlifts.com\/no\/projects\/villa-al-hamra\/","name":"Projects - Villa Al Hamra - SWIFT - 100% battery driven home lifts","isPartOf":{"@id":"https:\/\/swiftlifts.com\/no\/#website"},"datePublished":"2023-11-10T10:47:01+00:00","dateModified":"2026-03-09T14:04:45+00:00","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/no\/projects\/villa-al-hamra\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/no\/projects\/villa-al-hamra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/no\/projects\/villa-al-hamra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/no\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/swiftlifts.com\/no\/projects\/"},{"@type":"ListItem","position":3,"name":"Projects &#8211; Villa Al Hamra"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/no\/#website","url":"https:\/\/swiftlifts.com\/no\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/no\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/no\/","logo":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/swiftlifts.com\/no\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/no\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/no\/wp-json\/wp\/v2\/pages\/45556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/no\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/no\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/no\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/no\/wp-json\/wp\/v2\/comments?post=45556"}],"version-history":[{"count":1,"href":"https:\/\/swiftlifts.com\/no\/wp-json\/wp\/v2\/pages\/45556\/revisions"}],"predecessor-version":[{"id":57435,"href":"https:\/\/swiftlifts.com\/no\/wp-json\/wp\/v2\/pages\/45556\/revisions\/57435"}],"up":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/no\/wp-json\/wp\/v2\/pages\/45564"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/no\/wp-json\/wp\/v2\/media?parent=45556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}