{"id":43583,"date":"2024-08-04T14:05:08","date_gmt":"2024-08-04T14:05:08","guid":{"rendered":"https:\/\/swiftlifts.com\/projects-villa-taman-gelugor\/"},"modified":"2026-03-09T12:54:36","modified_gmt":"2026-03-09T12:54:36","slug":"projects-villa-taman-gelugor","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-taman-gelugor\/","title":{"rendered":"Projects &#8211; Villa Taman Gelugor"},"content":{"rendered":"\n\t<section class=\"section why_a_home_lift\" id=\"section_1468904521\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"633\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_hero_taman_gelugor.jpg\" class=\"bg attachment- size-\" alt=\"Project hero taman gelugor\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:90%\" id=\"row-2050018409\">\n\n\t<div id=\"col-2101840402\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2555675660\" class=\"text\">\n\t\t\n<h1>Villa Taman Gelugor<\/h1>\n\t\t\n<style>\n#text-2555675660 {\n  font-size: 2rem;\n  color: rgb(255, 255, 255);\n}\n#text-2555675660 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2101840402 > .col-inner {\n  margin: 200px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1468904521 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #dbe0d1;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1926764821\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-1053427050\">\n\n\t<div id=\"col-1586278501\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1727661926\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_18-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_18-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_18-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_18-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_18-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_18.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1727661926 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1586278501 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1586278501 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1965783874\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-293403041\" class=\"text\">\n\t\t\n<h2>Villa Taman Gelugor<\/h2>\n\t\t\n<style>\n#text-293403041 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-293403041 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-761357272\" class=\"text\">\n\t\t\n<p>Welcome to Villa Taman Gelugor \u2013 a brand new home from 2024 to the designer Ms Helen. As a designer, she had a strong vision herself when designing her three-floor villa with a SWIFT Pro in Gelugor on Penang Island. After many discussions and co-operation with her architect Blanc Designs, the result is a villa in modern minimalism, simple lines and with d\u00e9cor in white and glass allowing for a lot of natural sunlight. To make it convenient for the family to move between the different floors, Ms Helen decided to future proof her home and install a SWIFT Pro into the home.<\/p>\n<p><b>Model:<\/b> SWIFT Pro<br \/>\n<b>Floors:<\/b>\u00a03<br \/>\n<b>Lift Size: <\/b>Extra Large, XL (1400 x 1100mm)<br \/>\n<b>Lift Colour:<\/b> Traffic White (RAL 9016)<br \/>\n<b>ArtWall:<\/b>\u00a0Electric Opal<br \/>\n<b>Lift Carpet:<\/b>\u00a0Ege carpet, Linen Grey<br \/>\n<b>Location:<\/b> Taman Gelugor, Penang Island, Malaysia<\/p>\n\t\t\n<style>\n#text-761357272 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-761357272 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-right\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;background-color:rgb(255, 145, 150);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1965783874 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1965783874 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1926764821 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_990735443\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-751015599\">\n\n\t<div id=\"col-924180215\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_878466456\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_16-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_16-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_16-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_16-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_16-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_16.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_878466456 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3075256874\" class=\"text\">\n\t\t\n<p>The garden design is inspired by Japanese gardens and zen.<\/p>\n\t\t\n<style>\n#text-3075256874 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-3075256874 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-924180215 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-924180215 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2064642032\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2024343734\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_14-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_14-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_14-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_14-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_14-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_14.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2024343734 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1374364811\" class=\"text\">\n\t\t\n<p>Tiles in marble pattern were chosen due to its elegance and easy maintenance.<\/p>\n\t\t\n<style>\n#text-1374364811 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1374364811 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2064642032 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2064642032 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_990735443 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1839768177\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-855328557\">\n\n\t<div id=\"col-1954761405\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_686822424\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_02-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_02-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_02-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_02-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_02-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_02.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_686822424 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-4046691452\" class=\"text\">\n\t\t\n<p>The heart of the home is where the kitchen and SWIFT are located.<\/p>\n\t\t\n<style>\n#text-4046691452 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-4046691452 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1954761405 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1954761405 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1839768177 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_605264498\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-39309352\">\n\n\t<div id=\"col-2079506916\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1333534732\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_17-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_17-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_17-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_17-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_17-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_17.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1333534732 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1133268293\" class=\"text\">\n\t\t\n<p>Tea time. The Japanese inspired garden is an extension of the home and a place for reflection, meditation and a sense of harmony with nature.<\/p>\n\t\t\n<style>\n#text-1133268293 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1133268293 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2079506916 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2079506916 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1859140242\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_6323494\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_09-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_09-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_09-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_09-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_09-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_portrait_taman_gelugor_09.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_6323494 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2842310271\" class=\"text\">\n\t\t\n<p>SWIFT Pro in White, ArtWall in Electric Opal and Ege carpet in Linen Grey fits the interior in white, grey and black of Villa Taman Gelugor.<\/p>\n\t\t\n<style>\n#text-2842310271 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2842310271 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1859140242 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1859140242 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_605264498 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_951641410\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-867315984\">\n\n\t<div id=\"col-1367469014\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1568813274\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_04-1-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"project landscape taman gelugor\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_04-1-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_04-1-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_04-1-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_04-1-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/project_landscape_taman_gelugor_04-1.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1568813274 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3640722118\" class=\"text\">\n\t\t\n<p>Bright colors, lots of light, glas and mirrors give the house a lovely spaciousness.<\/p>\n\t\t\n<style>\n#text-3640722118 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-3640722118 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1367469014 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1367469014 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1044083940\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/projects\/\" class=\"button alert lowercase\" >\n\t\t<span>Click here to see more projects<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1044083940 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1044083940 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-601431112\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-pro-residential-lift\/\" class=\"button primary lowercase\" >\n\t\t<span>SWIFT Pro product page<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-601431112 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-601431112 > .col-inner {\n    padding: 0px 30% 0px 0%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_951641410 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":43670,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-43583","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Projects - Villa Taman Gelugor - SWIFT - 100% battery driven home lifts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-taman-gelugor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - Villa Taman Gelugor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-taman-gelugor\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T12:54:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/projects-villa-taman-gelugor\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/projects-villa-taman-gelugor\\\/\",\"name\":\"Projects - Villa Taman Gelugor - SWIFT - 100% battery driven home lifts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#website\"},\"datePublished\":\"2024-08-04T14:05:08+00:00\",\"dateModified\":\"2026-03-09T12:54:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/projects-villa-taman-gelugor\\\/#breadcrumb\"},\"inLanguage\":\"en-HK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/projects-villa-taman-gelugor\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/projects-villa-taman-gelugor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projects &#8211; Villa Taman Gelugor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-HK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-HK\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Projects - Villa Taman Gelugor - SWIFT - 100% battery driven home lifts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-taman-gelugor\/","og_locale":"en_US","og_type":"article","og_title":"Projects - Villa Taman Gelugor","og_url":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-taman-gelugor\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","article_modified_time":"2026-03-09T12:54:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-taman-gelugor\/","url":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-taman-gelugor\/","name":"Projects - Villa Taman Gelugor - SWIFT - 100% battery driven home lifts","isPartOf":{"@id":"https:\/\/swiftlifts.com\/hk\/#website"},"datePublished":"2024-08-04T14:05:08+00:00","dateModified":"2026-03-09T12:54:36+00:00","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-taman-gelugor\/#breadcrumb"},"inLanguage":"en-HK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-taman-gelugor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-taman-gelugor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/hk\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/swiftlifts.com\/hk\/projects\/"},{"@type":"ListItem","position":3,"name":"Projects &#8211; Villa Taman Gelugor"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/hk\/#website","url":"https:\/\/swiftlifts.com\/hk\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/hk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/hk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-HK"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/hk\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/hk\/","logo":{"@type":"ImageObject","inLanguage":"en-HK","@id":"https:\/\/swiftlifts.com\/hk\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/hk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/pages\/43583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/comments?post=43583"}],"version-history":[{"count":1,"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/pages\/43583\/revisions"}],"predecessor-version":[{"id":57422,"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/pages\/43583\/revisions\/57422"}],"up":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/pages\/43670"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/media?parent=43583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}