{"id":43543,"date":"2025-01-21T07:25:41","date_gmt":"2025-01-21T07:25:41","guid":{"rendered":"https:\/\/swiftlifts.com\/projects-villa-sala\/"},"modified":"2026-03-09T12:50:44","modified_gmt":"2026-03-09T12:50:44","slug":"projects-villa-sala","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-sala\/","title":{"rendered":"Projects &#8211; Villa Sala"},"content":{"rendered":"\n\t<section class=\"section why_a_home_lift\" id=\"section_1331754252\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"633\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_hero_sw107255.jpg\" class=\"bg attachment- size-\" alt=\"Villa Sala in Ho Chi Minh City\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:90%\" id=\"row-2050691607\">\n\n\t<div id=\"col-584554242\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3223361954\" class=\"text\">\n\t\t\n<h1>Villa Sala<\/h1>\n\t\t\n<style>\n#text-3223361954 {\n  font-size: 2rem;\n  color: rgb(255, 255, 255);\n}\n#text-3223361954 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-584554242 > .col-inner {\n  margin: 200px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1331754252 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #dbe0d1;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_833982865\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-1499277576\">\n\n\t<div id=\"col-1923290884\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_308906685\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1600\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_08.jpg\" class=\"attachment-original size-original\" alt=\"SWIFT Pro in Villa Sala.\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_08.jpg 1200w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_08-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_08-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_08-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_08-1152x1536.jpg 1152w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_308906685 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1923290884 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1923290884 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-813297590\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1865386519\" class=\"text\">\n\t\t\n<h2>Villa Sala<\/h2>\n\t\t\n<style>\n#text-1865386519 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1865386519 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-820315721\" class=\"text\">\n\t\t\n<p>Imagine enjoying the luxurious ambiance of a five-star resort without ever leaving home. At Villa Sala, you\u2019re surrounded by the beauty and serenity of a getaway, but with the unique comfort that only your own space can offer. While vacations are relaxing, there&#8217;s nothing quite like having all the services, conveniences, and privacy of a resort\u2014right where you belong.<\/p>\n<p>This is the home of a family of five who have found their perfect balance here. Nestled in one of Saigon\u2019s most beautiful areas, Villa Sala is located in the heart of the new urban development in Thu Thiem, District 2, Ho Chi Minh City. This Neoclassical-inspired home offers not just elegance, but practicality, including the installation of a SWIFT Pro homelift for modern living. With the 128-hectare Natural Ecological Park and the Saigon River just nearby, it provides the perfect blend of vibrant city life and peaceful nature. And with a private pool and spacious layout, the family can easily choose between quiet moments and social gatherings.\u00a0At Villa Sala, you don\u2019t have to choose between the joy of a vacation and the comfort of home\u2014you get the best of both worlds.<\/p>\n<p><b>Model:<\/b> SWIFT Pro<br \/>\n<b>Floors:<\/b>\u00a04<br \/>\n<b>Lift Size: <\/b>Extra Large, XL (1510&#215;1525 mm)<br \/>\n<b>Lift Colour:<\/b> Anthracite Grey<br \/>\n<b>ArtWall:<\/b> INK Bronze<br \/>\n<b>Lift Carpet:<\/b>\u00a0ege Carpet, Stitch Black<br \/>\n<b>Location:<\/b> Th\u1ee7\u00a0Thiem, District 2, Ho Chi Minh city aka Saigon<\/p>\n\t\t\n<style>\n#text-820315721 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-820315721 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-right\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;background-color:rgb(255, 145, 150);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-813297590 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-813297590 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_833982865 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1482929195\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1536377080\">\n\n\t<div id=\"col-1089085853\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_495772286\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_02-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"Details of SWIFT Pro in Villa Sala.\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_02-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_02-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_02-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_02-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_02.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_495772286 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-401991018\" class=\"text\">\n\t\t\n<p>SWIFT Pro in Anthracite Grey and ege Carpet in Stitch Black.<\/p>\n\t\t\n<style>\n#text-401991018 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-401991018 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1089085853 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1089085853 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1482929195 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1567562181\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-372134835\">\n\n\t<div id=\"col-1999968708\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_279660813\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_04-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"Entrance to Villa Sala.\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_04-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_04-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_04-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_04-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_04.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_279660813 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2390693672\" class=\"text\">\n\t\t\n<p>The first thing that greets you in Villa Sala &#8211; the SWIFT Pro.<\/p>\n\t\t\n<style>\n#text-2390693672 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2390693672 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1999968708 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1999968708 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1567562181 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1442663390\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1494044177\">\n\n\t<div id=\"col-62430748\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_428430631\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_01-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_01-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_01-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_01-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_01-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_01.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_428430631 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2304742738\" class=\"text\">\n\t\t\n<p>With the SWIFT Pro, you can choose between various light colors thanks to RGB. Here, in a blue shade.<\/p>\n\t\t\n<style>\n#text-2304742738 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-2304742738 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-62430748 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-62430748 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1931796789\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1799688311\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_05-600x800.jpg\" class=\"attachment-large size-large\" alt=\"Close-up of ArtWall INK Bronze and ege Carpet Stitch Black.\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_05-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_05-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_05-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_05-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_05.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1799688311 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-498446191\" class=\"text\">\n\t\t\n<p>Close-up of SWIFT Pro Anthracite Grey with ArtWall INK Bronze and ege Carpet Stitch Black.<\/p>\n\t\t\n<style>\n#text-498446191 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-498446191 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1931796789 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1931796789 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1442663390 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_957158507\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1569316548\">\n\n\t<div id=\"col-1434826245\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_955650614\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_06-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"SWIFT Pro as a center piece in Villa Sala.\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_06-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_06-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_06-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_06-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_06.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_955650614 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-708192785\" class=\"text\">\n\t\t\n<p>Can&#8217;t go wrong with different shades of black, grey and white.<\/p>\n\t\t\n<style>\n#text-708192785 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-708192785 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1434826245 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1434826245 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_957158507 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1003789202\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-763253222\">\n\n\t<div id=\"col-780792358\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_278863503\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_07-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_07-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_07-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_07-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_07-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/01\/project_sw107255_07.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_278863503 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-416657603\" class=\"text\">\n\t\t\n<p>SWIFT Pro&#8217;s ceiling and shaft with RBG light creating cool effects in the home of Villa Sala.<\/p>\n\t\t\n<style>\n#text-416657603 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-416657603 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-780792358 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-780792358 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1003789202 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_157992419\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1582351625\">\n\n\t<div id=\"col-896466880\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/projects\/\" class=\"button primary lowercase arrow-icon-button-sunset\" >\n\t\t<span>See All Projects<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-896466880 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-896466880 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1572509994\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-pro-residential-lift\/\" class=\"button primary lowercase arrow-icon-button-nordic-sunset\" >\n\t\t<span>SWIFT Pro<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1572509994 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1572509994 > .col-inner {\n    padding: 0px 30% 0px 0%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_157992419 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":43670,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-43543","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Projects - Villa Sala - SWIFT - 100% battery driven home lifts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-sala\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - Villa Sala\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-sala\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T12:50:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/projects-villa-sala\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/projects-villa-sala\\\/\",\"name\":\"Projects - Villa Sala - SWIFT - 100% battery driven home lifts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#website\"},\"datePublished\":\"2025-01-21T07:25:41+00:00\",\"dateModified\":\"2026-03-09T12:50:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/projects-villa-sala\\\/#breadcrumb\"},\"inLanguage\":\"en-HK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/projects-villa-sala\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/projects-villa-sala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projects &#8211; Villa Sala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-HK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-HK\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/hk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Projects - Villa Sala - SWIFT - 100% battery driven home lifts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-sala\/","og_locale":"en_US","og_type":"article","og_title":"Projects - Villa Sala","og_url":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-sala\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","article_modified_time":"2026-03-09T12:50:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-sala\/","url":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-sala\/","name":"Projects - Villa Sala - SWIFT - 100% battery driven home lifts","isPartOf":{"@id":"https:\/\/swiftlifts.com\/hk\/#website"},"datePublished":"2025-01-21T07:25:41+00:00","dateModified":"2026-03-09T12:50:44+00:00","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-sala\/#breadcrumb"},"inLanguage":"en-HK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-sala\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/hk\/projects\/projects-villa-sala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/hk\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/swiftlifts.com\/hk\/projects\/"},{"@type":"ListItem","position":3,"name":"Projects &#8211; Villa Sala"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/hk\/#website","url":"https:\/\/swiftlifts.com\/hk\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/hk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/hk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-HK"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/hk\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/hk\/","logo":{"@type":"ImageObject","inLanguage":"en-HK","@id":"https:\/\/swiftlifts.com\/hk\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/hk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/pages\/43543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/comments?post=43543"}],"version-history":[{"count":4,"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/pages\/43543\/revisions"}],"predecessor-version":[{"id":57413,"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/pages\/43543\/revisions\/57413"}],"up":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/pages\/43670"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/hk\/wp-json\/wp\/v2\/media?parent=43543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}