{"id":37737,"date":"2024-12-06T04:29:12","date_gmt":"2024-12-06T04:29:12","guid":{"rendered":"https:\/\/swiftlifts.com\/projects\/projects-villa-annabel\/"},"modified":"2024-12-23T10:42:55","modified_gmt":"2024-12-23T10:42:55","slug":"projects-villa-annabel","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/be\/projects\/projects-villa-annabel\/","title":{"rendered":"Projects &#8211; Villa Annabel"},"content":{"rendered":"\n\t<section class=\"section why_a_home_lift\" id=\"section_467852959\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"633\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_hero_sw105792.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:90%\" id=\"row-551327572\">\n\n\t<div id=\"col-806305597\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3666567250\" class=\"text\">\n\t\t\n<h1>Villa Annabel<\/h1>\n\t\t\n<style>\n#text-3666567250 {\n  font-size: 2rem;\n  color: rgb(255, 255, 255);\n}\n#text-3666567250 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-806305597 > .col-inner {\n  margin: 200px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_467852959 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #dbe0d1;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1638480679\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-57051009\">\n\n\t<div id=\"col-1690483528\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1448818363\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_09-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_09-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_09-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_09-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_09-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_09.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1448818363 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1690483528 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1690483528 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1559059093\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1258830720\" class=\"text\">\n\t\t\n<h2>Villa Annabel<\/h2>\n\t\t\n<style>\n#text-1258830720 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1258830720 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1547938545\" class=\"text\">\n\t\t\n<p>Welcome to Annabel &#8211; the Hamptons villa in Melbourne. This modern two-story villa, situated in Officer \u2013 a residential area in the outskirts of Melbourne, was completed in 2021. Three years later the family decided they wanted to future-proof their home and to install a SWIFT Pro into their house. Thankfully, a SWIFT home lift doesn\u2019t require any complicated building works. The Hamptons-style home, as you might now, originated on the East Coast of Long Island, America, in the beach house haven of affluent New Yorkers. However, over time this culture and Hamptons aesthetics have also been adopted by Australians as their \u2018own\u2019 \u2013 where this family, a couple with their dog, is one example. As Hamptons style embodies coastal, relaxed living, this modern Australian home embraces a love for the beach and indoor\/outdoor living too. Also, this Australian Hamptons home has a classic decor with timeless furniture pieces rather than what\u2019s on trend.<\/p>\n<p><b>Model:<\/b> SWIFT Pro<br \/>\n<b>Floors:<\/b> 2<br \/>\n<b>Lift Size: <\/b>Large, L (1200&#215;1000 mm)<br \/>\n<b>Lift Colour:<\/b> Traffic White<br \/>\n<b>ArtWall:<\/b> Harmonised Complexity<br \/>\n<b>Lift Carpet:<\/b> Linen Grey<br \/>\n<b>Location:<\/b> Officer, suburb to Melbourne<\/p>\n\t\t\n<style>\n#text-1547938545 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1547938545 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-right\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;background-color:rgb(255, 145, 150);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1559059093 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1559059093 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1638480679 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1252389871\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-640622759\">\n\n\t<div id=\"col-1946085355\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2122204139\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_01-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_01-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_01-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_01-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_01-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_01.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2122204139 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1450205213\" class=\"text\">\n\t\t\n<p>The exterior colour of a Hamptons villa is typically in tones of white, grey and cream &#8211; perfectly in tune with surrounding sandy beaches. The exterior of the weatherboard of Villa Annabel goes in a vanilla white and the foundation in grey.<\/p>\n\t\t\n<style>\n#text-1450205213 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1450205213 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1946085355 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1946085355 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1252389871 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1170337016\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1756619816\">\n\n\t<div id=\"col-1615866248\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_893171002\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_02-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_02-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_02-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_02-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_02-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_02.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_893171002 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3905030947\" class=\"text\">\n\t\t\n<p>The interior follows the same colour codings as the exterior and the walls are painted in a light grey and white. The first story has a wooden floor whereas the second story has a carpet in a stylish grey pattern.<\/p>\n\t\t\n<style>\n#text-3905030947 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-3905030947 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1615866248 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1615866248 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1170337016 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_207000638\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-415447322\">\n\n\t<div id=\"col-2123065199\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1229973543\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_04-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_04-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_04-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_04-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_04-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_04.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1229973543 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2203443487\" class=\"text\">\n\t\t\n<p>Take the SWIFT lift to your (home) office. The way to work from home.<\/p>\n\t\t\n<style>\n#text-2203443487 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2203443487 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2123065199 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2123065199 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_207000638 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1029507616\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-151398237\">\n\n\t<div id=\"col-1276387571\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1195359885\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_06-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_06-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_06-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_06-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_06-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_06.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1195359885 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1739237938\" class=\"text\">\n\t\t\n<p>Classic armchair in white and blue fits the Hamptons style interior.<\/p>\n\t\t\n<style>\n#text-1739237938 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-1739237938 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1276387571 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1276387571 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2109653483\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1361903622\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_05-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_05-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_05-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_05-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_05-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_05.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1361903622 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1069299721\" class=\"text\">\n\t\t\n<p>SWIFT Pro comes with RGB so that you can pick the colour of the day or whatever whenever you like.<\/p>\n\t\t\n<style>\n#text-1069299721 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-1069299721 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2109653483 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2109653483 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1029507616 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_665400848\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1723478385\">\n\n\t<div id=\"col-2010003619\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1371831291\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_08-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_08-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_08-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_08-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_08-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_08.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1371831291 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3153118420\" class=\"text\">\n\t\t\n<p>A view of the view \u2013 through SWIFT, right from home.<\/p>\n\t\t\n<style>\n#text-3153118420 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-3153118420 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2010003619 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2010003619 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-773239211\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1046930767\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_07-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_07-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_07-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_07-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_07-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_portrait_sw105792_07.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1046930767 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2753162551\" class=\"text\">\n\t\t\n<p>Different patterns of grey. ArtWall Harmonized Complexity Grey and Carpet in Linen Grey.<\/p>\n\t\t\n<style>\n#text-2753162551 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-2753162551 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-773239211 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-773239211 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_665400848 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1737267473\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-227750377\">\n\n\t<div id=\"col-1631373230\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_45288986\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"405\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_03-768x405.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_03-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_03-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_03-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_03-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/10\/project_landscape_sw105792_03.jpg 2000w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_45288986 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1675573400\" class=\"text\">\n\t\t\n<p>SWIFT Pro &#8211; with ArtWall Harmonised Complexity Grey &#8211; from above.<\/p>\n\t\t\n<style>\n#text-1675573400 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1675573400 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1631373230 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1631373230 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1737267473 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_862898962\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-792118067\">\n\n\t<div id=\"col-1274003086\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/projects\/\" class=\"button alert lowercase\" >\n\t\t<span>Click here to see more projects<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1274003086 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1274003086 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1696633539\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-pro-residential-lift\/\" class=\"button primary lowercase\" >\n\t\t<span>SWIFT Pro product page<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1696633539 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1696633539 > .col-inner {\n    padding: 0px 30% 0px 0%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_862898962 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":28674,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-37737","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Projecten - Villa Annabel - SWIFT Lifts<\/title>\n<meta name=\"description\" content=\"Villa Annabel beschikt over een SWIFT Pro-huislift, die Hamptons-stijl combineert met modern gemak. Gelegen in Melbourne, biedt het kust-elegantie en functionaliteit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/be\/projects\/projects-villa-annabel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - Villa Annabel\" \/>\n<meta property=\"og:description\" content=\"Villa Annabel beschikt over een SWIFT Pro-huislift, die Hamptons-stijl combineert met modern gemak. Gelegen in Melbourne, biedt het kust-elegantie en functionaliteit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/be\/projects\/projects-villa-annabel\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-23T10:42:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/projects\\\/projects-villa-annabel\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/projects\\\/projects-villa-annabel\\\/\",\"name\":\"Projecten - Villa Annabel - SWIFT Lifts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#website\"},\"datePublished\":\"2024-12-06T04:29:12+00:00\",\"dateModified\":\"2024-12-23T10:42:55+00:00\",\"description\":\"Villa Annabel beschikt over een SWIFT Pro-huislift, die Hamptons-stijl combineert met modern gemak. Gelegen in Melbourne, biedt het kust-elegantie en functionaliteit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/projects\\\/projects-villa-annabel\\\/#breadcrumb\"},\"inLanguage\":\"be-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/be\\\/projects\\\/projects-villa-annabel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/projects\\\/projects-villa-annabel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projecten\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projects &#8211; Villa Annabel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"be-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"be-BE\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Projecten - Villa Annabel - SWIFT Lifts","description":"Villa Annabel beschikt over een SWIFT Pro-huislift, die Hamptons-stijl combineert met modern gemak. Gelegen in Melbourne, biedt het kust-elegantie en functionaliteit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/be\/projects\/projects-villa-annabel\/","og_locale":"en_US","og_type":"article","og_title":"Projects - Villa Annabel","og_description":"Villa Annabel beschikt over een SWIFT Pro-huislift, die Hamptons-stijl combineert met modern gemak. Gelegen in Melbourne, biedt het kust-elegantie en functionaliteit.","og_url":"https:\/\/swiftlifts.com\/be\/projects\/projects-villa-annabel\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","article_modified_time":"2024-12-23T10:42:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/be\/projects\/projects-villa-annabel\/","url":"https:\/\/swiftlifts.com\/be\/projects\/projects-villa-annabel\/","name":"Projecten - Villa Annabel - SWIFT Lifts","isPartOf":{"@id":"https:\/\/swiftlifts.com\/be\/#website"},"datePublished":"2024-12-06T04:29:12+00:00","dateModified":"2024-12-23T10:42:55+00:00","description":"Villa Annabel beschikt over een SWIFT Pro-huislift, die Hamptons-stijl combineert met modern gemak. Gelegen in Melbourne, biedt het kust-elegantie en functionaliteit.","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/be\/projects\/projects-villa-annabel\/#breadcrumb"},"inLanguage":"be-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/be\/projects\/projects-villa-annabel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/be\/projects\/projects-villa-annabel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/be\/"},{"@type":"ListItem","position":2,"name":"Projecten","item":"https:\/\/swiftlifts.com\/be\/projects\/"},{"@type":"ListItem","position":3,"name":"Projects &#8211; Villa Annabel"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/be\/#website","url":"https:\/\/swiftlifts.com\/be\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"be-BE"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/be\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/be\/","logo":{"@type":"ImageObject","inLanguage":"be-BE","@id":"https:\/\/swiftlifts.com\/be\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/pages\/37737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/comments?post=37737"}],"version-history":[{"count":1,"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/pages\/37737\/revisions"}],"predecessor-version":[{"id":38928,"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/pages\/37737\/revisions\/38928"}],"up":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/pages\/28674"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/media?parent=37737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}