{"id":28704,"date":"2022-05-05T08:09:55","date_gmt":"2022-05-05T08:09:55","guid":{"rendered":"https:\/\/swiftlifts.com\/domestic-lifts\/"},"modified":"2026-02-16T14:20:08","modified_gmt":"2026-02-16T14:20:08","slug":"domestic-lifts","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/be\/domestic-lifts\/","title":{"rendered":"Huisliften"},"content":{"rendered":"\n\t<section class=\"section why_a_home_lift is-full-height\" id=\"section_793392094\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"494\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/03\/SW105082_07_our-home-lifts2-1-e1737441492960.jpg\" class=\"bg attachment-original size-original\" alt=\"our home lifts\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-2002953556\">\n\n\t<div id=\"col-663069500\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3855782442\" class=\"text\">\n\t\t\n<h1>Een huislift ontsluit het volledige potentieel van uw huis.<\/h1>\n\t\t\n<style>\n#text-3855782442 {\n  font-size: 2.3rem;\n  color: rgb(255,255,255);\n}\n#text-3855782442 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0px;margin-bottom:0px;max-width:80%;height:7px;background-color:rgb(255, 201, 189);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-663069500 > .col-inner {\n  padding: 0px 0px 0px 15%;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-2002953556 > .col > .col-inner {\n  padding: 50% 5% 5% 5%;\n}\n@media (min-width:550px) {\n  #row-2002953556 > .col > .col-inner {\n    padding: 35% 5% 5% 5%;\n  }\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_793392094 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 100vh;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section why_a_home_lift\" id=\"section_2014327621\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1956390973\">\n\n\t<div id=\"col-560746690\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-932855874\" class=\"text\">\n\t\t\n<h2>Een huislift maakt uw huis toekomstbestendig en verhoogt het comfort.<\/h2>\n\t\t\n<style>\n#text-932855874 {\n  font-size: 1.4rem;\n  color: rgb(0,0,0);\n}\n#text-932855874 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-660348101\" class=\"text\">\n\t\t\n<p>Heb je de keuken op de tweede verdieping? Genoeg van het sjouwen met zware spullen? Met een huislift kunt u comfortabel toegang krijgen tot alle verdiepingen van uw huis of de lift gebruiken om zware items te vervoeren. Een huislift verenigt families, verhoogt het comfort en voegt die extra alledaagse luxe toe.<\/p>\n\t\t\n<style>\n#text-660348101 {\n  font-size: 1.25rem;\n  color: #ff9196;\n}\n#text-660348101 > * {\n  color: #ff9196;\n}\n@media (min-width:550px) {\n  #text-660348101 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2146032770\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-4037564395\" class=\"text\">\n\t\t\n<h2>Een huislift is een slimme investering.<\/h2>\n\t\t\n<style>\n#text-4037564395 {\n  font-size: 1.4rem;\n  color: rgb(0,0,0);\n}\n#text-4037564395 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2764733400\" class=\"text\">\n\t\t\n<p>Uw huislift kan worden aangepast om prachtig in uw huis te passen, ongeacht het type huis, het aantal verdiepingen of de interieurstijl. Uw lift zorgt ervoor dat u niet hoeft te verhuizen wanneer u ouder wordt, en het maakt uw huis aantrekkelijk voor een breder publiek. Een huislift is gewoon een goede investering voor vele jaren.<\/p>\n\t\t\n<style>\n#text-2764733400 {\n  font-size: 1.25rem;\n  color: #ff9196;\n}\n#text-2764733400 > * {\n  color: #ff9196;\n}\n@media (min-width:550px) {\n  #text-2764733400 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1394982030\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"\/swift-pro\" class=\"button primary is-outline lowercase\" >\n\t\t<span>Meer over huisliften<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1394982030 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1394982030 > .col-inner {\n    margin: 20% 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1956390973 > .col > .col-inner {\n  padding: 10% 5% 0px 5%;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2014327621 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(250, 245, 242);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section swift_minimal_footprint\" id=\"section_1137819026\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t<div class=\"video-overlay no-click fill visible\"><\/div>\n\t<video class=\"video-bg fill visible\" preload playsinline autoplay muted loop>\n\t\t<source src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/SWIFT-Pro-360-product-overview_final2560px.mp4\" type=\"video\/mp4\"><source src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/08\/SWIFT-Pro-360-product-overview_final2560px.mp4\" type=\"video\/ogg\">\t<\/video>\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1070792927\">\n\n\t<div id=\"col-1782477791\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1307673750\" class=\"text\">\n\t\t\n<h2>Een huislift met een minimale ruimtebehoefte<\/h2>\n\t\t\n<style>\n#text-1307673750 {\n  font-size: 2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1782477791 > .col-inner {\n  padding: 0px 20px 0px 20px;\n}\n@media (min-width:550px) {\n  #col-1782477791 > .col-inner {\n    padding: 200px 0px 0px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1195789899\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1753058819\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2035605454\" class=\"text\">\n\t\t\n<h3><strong>De traditionele manieren werken niet<\/strong><\/h3>\n<p>Een <a href=\"https:\/\/swiftlifts.com\/en\/swift-faq\/what-types-of-elevators-are-there\/\">conventionele lift<\/a> vereist een veiligheidsschacht, een extra machinekamer, een externe schacht en deuren op elke verdieping. Als gevolg hiervan heeft de lift veel ruimte nodig. In een priv\u00e9woning wordt dit een probleem.<\/p>\n<h3><strong>SWIFT is compact<\/strong><\/h3>\n<p>SWIFT is een unieke huislift die gebruikmaakt van een platformliftoplossing. De platformlift heeft een ingebouwde machinekamer, een modulaire en allesomvattende schachtoplossing zonder de noodzaak van een externe schacht, extra deuren op de verdiepingen of ingewikkelde bouwwerkzaamheden zoals bij liften voor commerci\u00eble gebouwen. In tegenstelling tot traditionele liften kan SWIFT direct op de vloer worden ge\u00efnstalleerd of worden ingebouwd in een put van 50 mm. De totale ruimtebehoefte kan kleiner zijn dan die van een kledingkast.<\/p>\n<h3><strong>Een huislift draait op standaardstroom.<\/strong><\/h3>\n<p>De huislift van SWIFT is gebaseerd op een <a href=\"https:\/\/swiftlifts.com\/en\/swift-faq\/how-do-screw-driven-lifts-work\/\">schroef- en moeraandrijving<\/a>, wat betekent dat er geen olie nodig is zoals bij hydraulische liftoplossingen. Alle SWIFT-liften gebruiken standaard 230 V 1-fase, waardoor de extra kosten voor het voorbereiden van 3-fasen worden vermeden.<br \/>\n\t\t\n<style>\n#text-2035605454 {\n  font-size: 1.25rem;\n  text-align: left;\n  color: rgb(0,0,0);\n}\n#text-2035605454 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/swift-pro\" class=\"button primary is-outline lowercase\" >\n\t\t<span>Meer over liften voor thuis:<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1753058819 > .col-inner {\n  padding: 0px 20px 0px 20px;\n}\n@media (min-width:550px) {\n  #col-1753058819 > .col-inner {\n    padding: 100px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1137819026 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 100vh;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section swift-pro-hero\" id=\"section_330756220\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-center\"  id=\"row-512296623\">\n\n\t<div id=\"col-352457456\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative hide-for-medium\" id=\"slider-991024859\" >\n    <div class=\"slider slider-nav-dots-dashes slider-nav-simple slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 8000,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1314477912\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-1200x800.jpg\" class=\"attachment-large size-large\" alt=\"domestic lift with kids from SWIFT\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-1200x800.jpg 1200w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-600x400.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-768x512.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-1536x1024.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-e1737441678965.jpg 800w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1314477912 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_429631632\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-1200x800.jpg\" class=\"attachment-large size-large\" alt=\"domestic lift SWIFT wife and kids\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-1200x800.jpg 1200w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-600x400.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-768x512.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-1536x1024.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-e1737441646587.jpg 800w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_429631632 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t\n<style>\n#slider-991024859 .flickity-slider > * {\n  max-width: 100%!important;\n}\n<\/style>\n<\/div>\n\n\n<div class=\"slider-wrapper relative show-for-medium\" id=\"slider-1980957099\" >\n    <div class=\"slider slider-nav-dots-dashes slider-nav-simple slider-nav-large slider-nav-light slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 2000,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_645766944\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-1200x800.jpg\" class=\"attachment-large size-large\" alt=\"domestic lift SWIFT wife and kids\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-1200x800.jpg 1200w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-600x400.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-768x512.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-1536x1024.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH15_L-e1737441646587.jpg 800w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_645766944 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1012992065\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH12_L-1200x800.jpg\" class=\"attachment-large size-large\" alt=\"domestic lift SWIFT shopsticks\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH12_L-1200x800.jpg 1200w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH12_L-600x400.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH12_L-768x512.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH12_L-1536x1024.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH12_L.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1012992065 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1973553689\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH02_L-1200x800.jpg\" class=\"attachment-large size-large\" alt=\"Domestic lift SWIFT - husband and daughter\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH02_L-1200x800.jpg 1200w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH02_L-600x400.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH02_L-768x512.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH02_L-1536x1024.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH02_L.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1973553689 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_824241556\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-1200x800.jpg\" class=\"attachment-large size-large\" alt=\"domestic lift with kids from SWIFT\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-1200x800.jpg 1200w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-600x400.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-768x512.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-1536x1024.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH08_L-e1737441678965.jpg 800w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_824241556 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_388352471\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH17_L-1200x800.jpg\" class=\"attachment-large size-large\" alt=\"domestic lift SWIFT sporty wife\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH17_L-1200x800.jpg 1200w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH17_L-600x400.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH17_L-768x512.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH17_L-1536x1024.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT-Lite_SH17_L.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_388352471 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t\n<style>\n#slider-1980957099 .flickity-slider > * {\n  max-width: 100%!important;\n}\n<\/style>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-352457456 > .col-inner {\n  margin: 100px 0px 100px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_330756220 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(250, 245, 242);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section tesla_sec dark hide-for-medium\" id=\"section_434310028\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<p>&nbsp;<\/p>\n<div class=\"row row-full-width align-middle\"  id=\"row-1651428140\">\n\n\t<div id=\"col-1093773453\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2448138230\" class=\"text\">\n\t\t\n<div id=\"eco-drive-text-1\" class=\"eco-drive-text\">\n<div class=\"eco-drive-header\">EcoDrive &#8211; Minimaal energieverbruik<\/div>\n<div class=\"eco-drive-description\">De SWIFT huislift is uitgerust met de allernieuwste schroef- en moertechnologie (patent aangevraagd) uit Zweden. Het systeem is uiterst betrouwbaar, veilig en vereist minimaal onderhoud.<\/div>\n<\/div>\n\t\t\n<style>\n#text-2448138230 {\n  text-align: left;\n  color: #1fadb7;\n}\n#text-2448138230 > * {\n  color: #1fadb7;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-40956925\" class=\"text\">\n\t\t\n<div id=\"eco-drive-text-2\" class=\"eco-drive-text\">\n<div class=\"eco-drive-description\">SWIFT heeft een unieke EcoDrive-oplossing gebaseerd op een 48 V \/ 3kW batterijaangedreven IPM-SynRM-motor ge\u00efnspireerd op Tesla-technologie. Het aandrijfsysteem is voorzien van dynamische lading, waarbij de accu&#8217;s worden opgeladen als de liften naar beneden bewegen. Zo is elke 4e rit gratis en verbruikt de huislift bij normaal gebruik minder stroom dan een magnetron. Door onze optie voor zonnepanelen toe te voegen, is de lift vrijwel geheel onafhankelijk van het elektriciteitsnet.<\/div>\n<\/div>\n\t\t\n<style>\n#text-40956925 {\n  text-align: left;\n  color: #1fadb7;\n}\n#text-40956925 > * {\n  color: #1fadb7;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2216095347\" class=\"text\">\n\t\t\n<div id=\"eco-drive-text-3\" class=\"eco-drive-text\">\n<div class=\"eco-drive-header\">Zoet geluid van stilte<\/div>\n<div class=\"eco-drive-description\">Doet iemand bij u thuis een dutje? De SWIFT-huislift heeft speciaal ontworpen aluminium geleiders en zachte polyurethaanwielen, waardoor we een van de soepelste en stilste huisliften op de markt kunnen aanbieden.<\/div>\n<\/div>\n\t\t\n<style>\n#text-2216095347 {\n  text-align: left;\n  color: #1fadb7;\n}\n#text-2216095347 > * {\n  color: #1fadb7;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_434310028 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 860vh;\n  background-color: rgb(0,0,0);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section why_a_home_lift is-full-height\" id=\"section_1760334307\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1547\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT_detail_01-scaled.jpg\" class=\"bg attachment- size-\" alt=\"SWIFT detail\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:80%\" id=\"row-1494877116\">\n\n\t<div id=\"col-2092022512\" class=\"col medium-12 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  data-parallax-fade=\"true\" data-parallax=\"2\">\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2092022512 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1446328732\" class=\"col hide-for-medium medium-12 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-26848619\" class=\"col hide-for-medium medium-12 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-26848619 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\" style=\"max-width:80%\" id=\"row-1452861607\">\n\n\t<div id=\"col-1580070017\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2007790991\" class=\"text\">\n\t\t\n<h2>Een huislift met slim design<\/h2>\n<p>Scandinavisch minimalisme verlegt de grenzen van wat hedendaags design voor een huis kan betekenen. Milieuvriendelijke materialen voor vloeren, designstatement ArtWalls en kleuren die ervoor zorgen dat uw huislift opvalt of opvalt. SWIFT is een lift die geen concessies doet aan kwaliteit en veiligheid, boordevol slimme functies voor een echt gezinsleven.<br \/>\n\t\t\n<style>\n#text-2007790991 {\n  font-size: 1.5rem;\n  color: rgb(219, 224, 209);\n}\n#text-2007790991 > * {\n  color: rgb(219, 224, 209);\n}\n@media (min-width:550px) {\n  #text-2007790991 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/swiftlifts.com\/swift-faq\/\" class=\"button secondary is-outline lowercase\" >\n\t\t<span>Binnenlandse liftprijzen<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1580070017 > .col-inner {\n  padding: 0 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-278755884\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1760334307 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n  min-height: 100vh;\n  background-color: rgb(0,0,0);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section two_models_comparison_sec\" id=\"section_1967662813\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-bottom align-center\" style=\"max-width:80%\" id=\"row-244014938\">\n\n\t<div id=\"col-645174192\" class=\"col medium-12 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-4014797563\" class=\"text\">\n\t\t\n<h2>SWIFT comes in 2 models.<\/h2>\n\t\t\n<style>\n#text-4014797563 {\n  font-size: 2rem;\n  color: rgb(0,0,0);\n}\n#text-4014797563 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-645174192 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-244014938 > .col > .col-inner {\n  padding: 100px 0px 0px 0px;\n  background-color: rgb(250, 245, 242);\n}\n<\/style>\n<\/div>\n\n<div class=\"row row-full-width\"  id=\"row-1455992779\">\n\n\t<div id=\"col-2079385681\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1964790690\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/10\/SWIFT-Pro-comparison-image.jpg\" \/><\/p>\n<h2>SWIFT Pro<\/h2>\n<p class=\"swift-comparison-pro-text\">SWIFT Pro is onze meest geavanceerde thuislift met verschillende opties voor gepersonaliseerde instellingen. Verkrijgbaar in 4 maten en 5 verschillende kleuren met een capaciteit van 250 kg &#8211; 400 kg. Verschillende vloeropties van het Deense designbedrijf Ege Carpets, een van Europa&#8217;s toonaangevende fabrikanten van duurzame hoogwaardige tapijten.<\/p>\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-pro-residential-lift\/\" class=\"button primary is-outline lowercase\" >\n\t\t<span>SWIFT Pro home lift<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-415376756\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/10\/SWIFT-Lite-comparison-image.jpg\" \/><\/p>\n<h2 class=\"swift-comparison-lite-header\">SWIFT Lite<\/h2>\n<p>SWIFT Lite is onze basis thuislift, ontworpen om te voldoen aan de eisen van een beperkt budget zonder concessies te doen aan stijl en comfort. Verkrijgbaar in 4 maten en 3 verschillende kleuren met een capaciteit van 250 kg &#8211; 400 kg.<\/p>\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-lite-a-small-house-lift\/\" class=\"button alert is-outline lowercase\" >\n\t\t<span>SWIFT Lite thuislift<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2007257003\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1208656261\" class=\"col hide-for-medium medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2014364504\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<section class=\"swift-comparison-table\">Tapijten:<img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/1-2.png\" width=\"20px\" \/><img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/2-2.png\" width=\"20px\" \/><img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/3-2.png\" width=\"20px\" \/><img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/4-2.png\" width=\"20px\" \/><img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/5-1.png\" width=\"20px\" \/><img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/una_micro.jpg\" width=\"20px\" \/><img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/1-2.png\" width=\"20px\" \/><\/p>\n<table>\n<tbody>\n<tr>\n<th><\/th>\n<th class=\"table-header-pro\">SWIFT Pro<\/th>\n<th class=\"table-header-lite\">SWIFT Lite<\/th>\n<\/tr>\n<p><!-- Example rows, repeat as necessary --><\/p>\n<tr>\n<td>Kleuren:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/1-1.png\" width=\"20px\" \/> <img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/2-1.png\" width=\"20px\" \/> <img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/4-3.png\" width=\"20px\" \/> <img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/3-1.png\" width=\"20px\" \/> <img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/10\/4-4.jpg\" width=\"20px\" \/><\/td>\n<td class=\"underline-lite\"><img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/1-1.png\" width=\"20px\" \/> <img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/05\/3-1.png\" width=\"20px\" \/> <img decoding=\"async\" class=\"comparison-image\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/10\/4-4.jpg\" width=\"20px\" \/><\/td>\n<\/tr>\n<tr>\n<td>EcoDrive met dynamische oplading:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<\/tr>\n<tr>\n<td>Anti-trap:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<\/tr>\n<tr>\n<td>Batterij aangedreven:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<\/tr>\n<tr>\n<td>Emergency lowering\u00b9:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<\/tr>\n<tr>\n<td>Double glass with built in auto opener\/closer:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<\/tr>\n<tr>\n<td>SWIFT Remote\u00b2:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<\/tr>\n<tr>\n<td>Warranty\u00b3:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<\/tr>\n<tr>\n<td>Safety certification\u2074:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<\/tr>\n<tr>\n<td>10\u201d dynamic Touch display:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>ArtWall with LED:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Ceiling with LED:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Shaft light\u2075:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Adjustable lift speed\u2076:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Adjustable door speed:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Adjustable shaft and carrier lights:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Bottom cover:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Prepared for smart homes:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Music \/ audio:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Ergo features:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Instructions to users:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Child lock:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Hold doors open function:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Locking of floors:<\/td>\n<td class=\"underline-pro\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"underline-lite\">&#8211;<\/td>\n<\/tr>\n<tr>\n<td>Personalized naming of floors:<\/td>\n<td class=\"\"><img decoding=\"async\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/09\/yes.png\" width=\"15px\" \/><\/td>\n<td class=\"\">&#8211;<\/td>\n<\/tr>\n<p><!-- Add more rows as per your requirement --><\/tbody>\n<\/table>\n<\/section>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2014364504 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 50px 0px;\n}\n@media (min-width:550px) {\n  #col-2014364504 > .col-inner {\n    margin: 0px 0px 50px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-663851049\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-157318783\" class=\"text\">\n\t\t\n<p>1) Possible to change speed from display.<br \/>\n2) Optioneel<br \/>\n3) 5 year + 10 years of drive system<br \/>\n4) European Machinery Directive 2006\/42\/EC<br \/>\n5) White as standard. RGB optional.<br \/>\n6) Full operation<\/p>\n\t\t\n<style>\n#text-157318783 {\n  font-size: 0.75rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1967662813 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n  min-height: 44vh;\n  background-color: rgb(250, 245, 242);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section sizes_sec\" id=\"section_513267538\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1308\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2023\/10\/VS-1.jpg\" class=\"bg attachment- size-\" alt=\"SWIFT Pro vs Lite\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-small align-bottom\" style=\"max-width:80%\" id=\"row-1477240487\">\n\n\t<div id=\"col-289794172\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2080903596\" class=\"text\">\n\t\t\n<p>SWIFT Pro has a dynamic touch display with advanced features and customisable interface.<\/p>\n\t\t\n<style>\n#text-2080903596 {\n  color: #ff9196;\n}\n#text-2080903596 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/swift-pro-residential-lift\" class=\"button primary lowercase\" >\n\t\t<span>SWIFT Pro home lift<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-289794172 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-289794172 > .col-inner {\n    padding: 0px 0px 100px 0px;\n    margin: 80% 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-301384060\" class=\"col hide-for-medium medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1180583955\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3077816336\" class=\"text\">\n\t\t\n<p>SWIFT Lite comes with classic push buttons.<\/p>\n\t\t\n<style>\n#text-3077816336 {\n  color: rgb(30, 98, 122);\n}\n#text-3077816336 > * {\n  color: rgb(30, 98, 122);\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-lite-a-small-house-lift\/\" class=\"button alert lowercase\" >\n\t\t<span>SWIFT Lite thuislift<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1180583955 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1180583955 > .col-inner {\n    padding: 0px 0px 100px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1477240487 > .col > .col-inner {\n  padding: 50px 0px 50px 0px;\n}\n@media (min-width:550px) {\n  #row-1477240487 > .col > .col-inner {\n    padding: 90% 0px 100px 0px;\n  }\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_513267538 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n  min-height: 44vh;\n  background-color: rgb(250, 245, 242);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":28705,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-28704","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Luxe Huislift: Comfort Thuis Toevoegen<\/title>\n<meta name=\"description\" content=\"Huisliften die jarenlang luxe en echt comfort bieden aan uw huis. Kies tussen verschillende maten en functies. Eenvoudige installatie. Lees meer\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/be\/domestic-lifts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Huisliften\" \/>\n<meta property=\"og:description\" content=\"Huisliften die jarenlang luxe en echt comfort bieden aan uw huis. Kies tussen verschillende maten en functies. Eenvoudige installatie. Lees meer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/be\/domestic-lifts\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-16T14:20:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2021\/09\/SWIFT_Pro_Living_room_v2_Mobil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"953\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/domestic-lifts\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/domestic-lifts\\\/\",\"name\":\"Luxe Huislift: Comfort Thuis Toevoegen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/domestic-lifts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/domestic-lifts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/SWIFT_Pro_Living_room_v2_Mobil.jpg\",\"datePublished\":\"2022-05-05T08:09:55+00:00\",\"dateModified\":\"2026-02-16T14:20:08+00:00\",\"description\":\"Huisliften die jarenlang luxe en echt comfort bieden aan uw huis. Kies tussen verschillende maten en functies. Eenvoudige installatie. Lees meer\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/domestic-lifts\\\/#breadcrumb\"},\"inLanguage\":\"be-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/be\\\/domestic-lifts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"be-BE\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/domestic-lifts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/SWIFT_Pro_Living_room_v2_Mobil.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/SWIFT_Pro_Living_room_v2_Mobil.jpg\",\"width\":953,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/domestic-lifts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Huisliften\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"be-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"be-BE\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Luxe Huislift: Comfort Thuis Toevoegen","description":"Huisliften die jarenlang luxe en echt comfort bieden aan uw huis. Kies tussen verschillende maten en functies. Eenvoudige installatie. Lees meer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/be\/domestic-lifts\/","og_locale":"en_US","og_type":"article","og_title":"Huisliften","og_description":"Huisliften die jarenlang luxe en echt comfort bieden aan uw huis. Kies tussen verschillende maten en functies. Eenvoudige installatie. Lees meer","og_url":"https:\/\/swiftlifts.com\/be\/domestic-lifts\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","article_modified_time":"2026-02-16T14:20:08+00:00","og_image":[{"width":953,"height":1440,"url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2021\/09\/SWIFT_Pro_Living_room_v2_Mobil.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/be\/domestic-lifts\/","url":"https:\/\/swiftlifts.com\/be\/domestic-lifts\/","name":"Luxe Huislift: Comfort Thuis Toevoegen","isPartOf":{"@id":"https:\/\/swiftlifts.com\/be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swiftlifts.com\/be\/domestic-lifts\/#primaryimage"},"image":{"@id":"https:\/\/swiftlifts.com\/be\/domestic-lifts\/#primaryimage"},"thumbnailUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2021\/09\/SWIFT_Pro_Living_room_v2_Mobil.jpg","datePublished":"2022-05-05T08:09:55+00:00","dateModified":"2026-02-16T14:20:08+00:00","description":"Huisliften die jarenlang luxe en echt comfort bieden aan uw huis. Kies tussen verschillende maten en functies. Eenvoudige installatie. Lees meer","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/be\/domestic-lifts\/#breadcrumb"},"inLanguage":"be-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/be\/domestic-lifts\/"]}]},{"@type":"ImageObject","inLanguage":"be-BE","@id":"https:\/\/swiftlifts.com\/be\/domestic-lifts\/#primaryimage","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2021\/09\/SWIFT_Pro_Living_room_v2_Mobil.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2021\/09\/SWIFT_Pro_Living_room_v2_Mobil.jpg","width":953,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/be\/domestic-lifts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/be\/"},{"@type":"ListItem","position":2,"name":"Huisliften"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/be\/#website","url":"https:\/\/swiftlifts.com\/be\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"be-BE"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/be\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/be\/","logo":{"@type":"ImageObject","inLanguage":"be-BE","@id":"https:\/\/swiftlifts.com\/be\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/pages\/28704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/comments?post=28704"}],"version-history":[{"count":3,"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/pages\/28704\/revisions"}],"predecessor-version":[{"id":50199,"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/pages\/28704\/revisions\/50199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/media\/28705"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/be\/wp-json\/wp\/v2\/media?parent=28704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}