{"id":56700,"date":"2024-12-03T06:25:45","date_gmt":"2024-12-03T06:25:45","guid":{"rendered":"https:\/\/swiftlifts.com\/projects-townhouse-classia-khang-dien\/"},"modified":"2024-12-03T06:25:45","modified_gmt":"2024-12-03T06:25:45","slug":"projects-townhouse-classia-khang-dien","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/be-fr\/projects\/projects-townhouse-classia-khang-dien\/","title":{"rendered":"Projects &#8211; Townhouse Classia Khang Dien"},"content":{"rendered":"\n\t<section class=\"section why_a_home_lift\" id=\"section_325014029\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"633\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_hero_sw107255.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:90%\" id=\"row-804903963\">\n\n\t<div id=\"col-1344544081\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-48196372\" class=\"text\">\n\t\t\n<h1>Townhouse Classia Khang Dien<\/h1>\n\t\t\n<style>\n#text-48196372 {\n  font-size: 2rem;\n  color: rgb(255, 255, 255);\n}\n#text-48196372 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1344544081 > .col-inner {\n  margin: 200px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_325014029 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #dbe0d1;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_2060879053\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-899132198\">\n\n\t<div id=\"col-776212336\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1370257926\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_05.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1370257926 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-776212336 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-776212336 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1934010213\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3452850228\" class=\"text\">\n\t\t\n<h2>Townhouse Classia Khang Dien<\/h2>\n\t\t\n<style>\n#text-3452850228 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-3452850228 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2209673023\" class=\"text\">\n\t\t\n<p>Lover of Neo-Classic French Architecture? Then, welcome to this four-story townhouse with a SWIFT Pro at hand (or feet) in the Th\u1ee7 \u0110\u1ee9c district of vibrant Ho Chi Minh City, also known as Saigon.<\/p>\n<p>Completed in 2024, the brand-new Classia Khang Dien is a modern masterpiece with a timeless blend of classical and contemporary elements. Classic architectural features like corinthian columns, arches, and decorative motifs are thoughtfully paired with modern amenities such as tempered glass, stainless steel, smart lighting systems, and its very own home lift. The interior of the Townhouse Classia Khang Dien is carefully curated, combining style and quality. Premium materials like natural wood, marble, and metal come together to create a cozy yet luxurious vibe. The perfect harmony of colors and natural light brings a relaxing and refined atmosphere for the whole family, with nature just next door.<\/p>\n<p><b>Model:<\/b> SWIFT Pro<br \/>\n<b>Floors:<\/b> 4<br \/>\n<b>Lift Size: <\/b>Small, S (830&#215;1000 mm)<br \/>\n<b>Lift Colour:<\/b> Traffic White<br \/>\n<b>ArtWall:<\/b> INK Bronze<br \/>\n<b>Lift Carpet:<\/b> Linen Grey<br \/>\n<b>Location:<\/b> Th\u1ee7 \u0110\u1ee9c district, Ho Chi Minh City aka Saigon<\/p>\n\t\t\n<style>\n#text-2209673023 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2209673023 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-right\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;background-color:rgb(255, 145, 150);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1934010213 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1934010213 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2060879053 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_673381392\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1552497682\">\n\n\t<div id=\"col-2050730672\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_873181956\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_09.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_873181956 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3540477058\" class=\"text\">\n\t\t\n<p>SWIFT Pro in Traffic White, paired with a Linen Grey carpet and the ArtWall INK Bronze, beautifully complements a light-colored interior with wood and marble. Elegant and harmonious at the same time.<\/p>\n\t\t\n<style>\n#text-3540477058 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-3540477058 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2050730672 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2050730672 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_673381392 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_216823544\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1426874574\">\n\n\t<div id=\"col-1676027126\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1972948744\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"405\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12-768x405.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_12.jpg 2000w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1972948744 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-656835648\" class=\"text\">\n\t\t\n<p>Different shades of beige create a sense of calm in the Classia Khang Dien Townhouse.<\/p>\n\t\t\n<style>\n#text-656835648 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-656835648 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1676027126 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1676027126 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_216823544 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_186268606\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-360766715\">\n\n\t<div id=\"col-804539917\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_41052422\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_03.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_41052422 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3507256968\" class=\"text\">\n\t\t\n<p>Side by side. Outside, the neoclassical French-style exterior, adorned with corinthian columns and beautiful details, embodies timeless elegance and sophistication.<\/p>\n\t\t\n<style>\n#text-3507256968 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-3507256968 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-804539917 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-804539917 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1734564764\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_73404032\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_04.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_73404032 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-563328051\" class=\"text\">\n\t\t\n<p>Inside, a contemporary oasis: modern elements like tempered glass and smart lighting systems blend seamlessly with the convenience of a private home lift.<\/p>\n\t\t\n<style>\n#text-563328051 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-563328051 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1734564764 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1734564764 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_186268606 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_434614693\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1851081767\">\n\n\t<div id=\"col-616455548\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1865039360\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_02.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1865039360 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2926408627\" class=\"text\">\n\t\t\n<p>It&rsquo;s all in the details.<\/p>\n\t\t\n<style>\n#text-2926408627 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-2926408627 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-616455548 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-616455548 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1211559415\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1402956315\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_portrait_sw107255_07.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1402956315 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-4283885756\" class=\"text\">\n\t\t\n<p>Perfect harmony: the SWIFT Pro carpet and marble floor share a stunning color palette.<\/p>\n\t\t\n<style>\n#text-4283885756 {\n  font-size: 1rem;\n  color: #ff9196;\n}\n#text-4283885756 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1211559415 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1211559415 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_434614693 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_181399345\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1072940269\">\n\n\t<div id=\"col-1407936553\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1217167384\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_16.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1217167384 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2868543966\" class=\"text\">\n\t\t\n<p>Classia Kheng Dien Townhouse &#8211; a timeless blend of classical and contemporary elements.<\/p>\n\t\t\n<style>\n#text-2868543966 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2868543966 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1407936553 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1407936553 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_181399345 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_86457833\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-2013031966\">\n\n\t<div id=\"col-64222007\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_622383138\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"405\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14-768x405.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_14.jpg 2000w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_622383138 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2635550958\" class=\"text\">\n\t\t\n<p>The townhouse is dominated by white and earthy tones, making it especially striking that you can change the color and intensity of the SWIFT Pro shaft light with a simple touch.<\/p>\n\t\t\n<style>\n#text-2635550958 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2635550958 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-64222007 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-64222007 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_86457833 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1067455896\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-44110194\">\n\n\t<div id=\"col-443531947\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1797295094\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/09\/project_landscape_sw107255_07.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1797295094 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2414062323\" class=\"text\">\n\t\t\n<p>SWIFT Pro&rsquo;s RGB colors come in every color of the rainbow. Here in Frozen blue.<\/p>\n\t\t\n<style>\n#text-2414062323 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2414062323 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-443531947 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-443531947 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1067455896 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1219596577\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-485880157\">\n\n\t<div id=\"col-1232297471\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/projects\/\" class=\"button alert lowercase\" >\n\t\t<span>Click here to see more projects<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1232297471 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1232297471 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-276962596\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-pro-residential-lift\/\" class=\"button primary lowercase\" >\n\t\t<span>SWIFT Pro product page<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-276962596 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-276962596 > .col-inner {\n    padding: 0px 30% 0px 0%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1219596577 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":56737,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-56700","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Projecten - Townhouse Classia Khang Dien - SWIFT Lifts<\/title>\n<meta name=\"description\" content=\"Townhouse Classia Khang Dien beschikt over SWIFT Pro-liften en combineert neoklassieke Franse architectuur met moderne luxe in de levendige wijk Th\u1ee7 \u0110\u1ee9c in Saigon.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/be-fr\/projects\/projects-townhouse-classia-khang-dien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - Townhouse Classia Khang Dien\" \/>\n<meta property=\"og:description\" content=\"Townhouse Classia Khang Dien beschikt over SWIFT Pro-liften en combineert neoklassieke Franse architectuur met moderne luxe in de levendige wijk Th\u1ee7 \u0110\u1ee9c in Saigon.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/be-fr\/projects\/projects-townhouse-classia-khang-dien\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/projects\\\/projects-townhouse-classia-khang-dien\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/projects\\\/projects-townhouse-classia-khang-dien\\\/\",\"name\":\"Projecten - Townhouse Classia Khang Dien - SWIFT Lifts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/#website\"},\"datePublished\":\"2024-12-03T06:25:45+00:00\",\"description\":\"Townhouse Classia Khang Dien beschikt over SWIFT Pro-liften en combineert neoklassieke Franse architectuur met moderne luxe in de levendige wijk Th\u1ee7 \u0110\u1ee9c in Saigon.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/projects\\\/projects-townhouse-classia-khang-dien\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/projects\\\/projects-townhouse-classia-khang-dien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/projects\\\/projects-townhouse-classia-khang-dien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projecten\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projects &#8211; Townhouse Classia Khang Dien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/be-fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Projecten - Townhouse Classia Khang Dien - SWIFT Lifts","description":"Townhouse Classia Khang Dien beschikt over SWIFT Pro-liften en combineert neoklassieke Franse architectuur met moderne luxe in de levendige wijk Th\u1ee7 \u0110\u1ee9c in Saigon.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/be-fr\/projects\/projects-townhouse-classia-khang-dien\/","og_locale":"fr_FR","og_type":"article","og_title":"Projects - Townhouse Classia Khang Dien","og_description":"Townhouse Classia Khang Dien beschikt over SWIFT Pro-liften en combineert neoklassieke Franse architectuur met moderne luxe in de levendige wijk Th\u1ee7 \u0110\u1ee9c in Saigon.","og_url":"https:\/\/swiftlifts.com\/be-fr\/projects\/projects-townhouse-classia-khang-dien\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/be-fr\/projects\/projects-townhouse-classia-khang-dien\/","url":"https:\/\/swiftlifts.com\/be-fr\/projects\/projects-townhouse-classia-khang-dien\/","name":"Projecten - Townhouse Classia Khang Dien - SWIFT Lifts","isPartOf":{"@id":"https:\/\/swiftlifts.com\/be-fr\/#website"},"datePublished":"2024-12-03T06:25:45+00:00","description":"Townhouse Classia Khang Dien beschikt over SWIFT Pro-liften en combineert neoklassieke Franse architectuur met moderne luxe in de levendige wijk Th\u1ee7 \u0110\u1ee9c in Saigon.","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/be-fr\/projects\/projects-townhouse-classia-khang-dien\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/be-fr\/projects\/projects-townhouse-classia-khang-dien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/be-fr\/projects\/projects-townhouse-classia-khang-dien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/en\/"},{"@type":"ListItem","position":2,"name":"Projecten","item":"https:\/\/swiftlifts.com\/be-fr\/projects\/"},{"@type":"ListItem","position":3,"name":"Projects &#8211; Townhouse Classia Khang Dien"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/be-fr\/#website","url":"https:\/\/swiftlifts.com\/be-fr\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/be-fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/be-fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/be-fr\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/be-fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/swiftlifts.com\/be-fr\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/be-fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/be-fr\/wp-json\/wp\/v2\/pages\/56700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/be-fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/be-fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/be-fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/be-fr\/wp-json\/wp\/v2\/comments?post=56700"}],"version-history":[{"count":0,"href":"https:\/\/swiftlifts.com\/be-fr\/wp-json\/wp\/v2\/pages\/56700\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/be-fr\/wp-json\/wp\/v2\/pages\/56737"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/be-fr\/wp-json\/wp\/v2\/media?parent=56700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}