{"id":52820,"date":"2025-09-22T04:49:05","date_gmt":"2025-09-22T04:49:05","guid":{"rendered":"https:\/\/swiftlifts.com\/projects\/projects-bungalow-taman-naluri-emas\/"},"modified":"2025-09-22T04:49:37","modified_gmt":"2025-09-22T04:49:37","slug":"projects-bungalow-taman-naluri-emas","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/au\/projects\/projects-bungalow-taman-naluri-emas\/","title":{"rendered":"Projects &#8211; Bungalow Taman Naluri Emas"},"content":{"rendered":"\n\t<section class=\"section why_a_home_lift\" id=\"section_1912288694\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"633\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_hero_SW107927.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:90%\" id=\"row-1361764873\">\n\n\t<div id=\"col-1219439392\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1794010864\" class=\"text\">\n\t\t\n<h1>Bungalow Taman Naluri Emas<\/h1>\n\t\t\n<style>\n#text-1794010864 {\n  font-size: 2rem;\n  color: rgb(255, 255, 255);\n}\n#text-1794010864 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1219439392 > .col-inner {\n  margin: 200px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1912288694 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #dbe0d1;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1262261221\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-2142044955\">\n\n\t<div id=\"col-1952630968\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_157822733\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_01-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_01-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_01-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_01-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_01-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_01.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_157822733 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1952630968 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1952630968 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-551422376\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1408996233\" class=\"text\">\n\t\t\n<h2>Bungalow Taman Naluri Emas<\/h2>\n\t\t\n<style>\n#text-1408996233 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1408996233 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-185015863\" class=\"text\">\n\t\t\n<p>Tucked away in the exclusive Primero Garden in Seberang Jaya, Penang, this multi-storey bungalow is more than just a beautiful house \u2013 it\u2019s a home built for everyday life, comfort, and connection.<\/p>\n<p>Here, a family enjoys the quiet of a secure, private enclave while staying just minutes from shopping, schools, and the Penang Bridge. Their days flow between lush garden surroundings and moments spent at the contemporary clubhouse just around the corner. With six spacious bedrooms \u2013 each with its own en-suite \u2013 this home is offering privacy and ease across all the floors. Premium finishes run throughout, offering a refined backdrop to daily routines, weekend gatherings, and quiet evenings in.   <\/p>\n<p>And with the SWIFT Pro at the heart of it all, movement between floors is effortless \u2013 whether carrying groceries, helping grandparents upstairs, or simply enjoying a smooth, quiet ride with a morning coffee in hand.<\/p>\n<p><b>Model:<\/b> SWIFT Pro<br \/><b>Floors:<\/b> 3<br \/><b>Lift Size: <\/b>XL (1450*1465)<br \/><b>Lift Colour:<\/b> Traffic White<br \/><b>ArtWall:<\/b> Oriental White<br \/><b>Lift Carpet:<\/b> ege Stitch Black<br \/><b>Location:<\/b> Seberang Jaya, Penang \u2013 Malaysia<\/p>\n\t\t\n<style>\n#text-185015863 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-185015863 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-right\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;background-color:rgb(255, 145, 150);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-551422376 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-551422376 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1262261221 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1109865932\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-581904273\">\n\n\t<div id=\"col-220487455\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1639014922\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_10-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_10-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_10-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_10-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_10-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_10.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1639014922 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1022897865\" class=\"text\">\n\t\t\n<p>For this family, the open-plan kitchen and living room is just right \u2013 always ready for dinners, chats, and spontaneous get-togethers.<\/p>\n\t\t\n<style>\n#text-1022897865 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1022897865 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-220487455 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-220487455 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1109865932 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_190089873\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-919321208\">\n\n\t<div id=\"col-1418482799\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1623633804\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_03-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_03-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_03-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_03-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_03-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_03.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1623633804 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2902913705\" class=\"text\">\n\t\t\n<p>This multi-level bungalow in Primero Garden, Penang, combines luxury and practicality.<\/p>\n\t\t\n<style>\n#text-2902913705 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2902913705 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1418482799 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1418482799 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-763839522\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1745945787\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_05-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_05-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_05-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_05-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_05-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_05.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1745945787 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2432390462\" class=\"text\">\n\t\t\n<p>Light and patterns in intriguing combinations.<\/p>\n\t\t\n<style>\n#text-2432390462 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2432390462 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-763839522 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-763839522 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_190089873 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_775935982\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-352187318\">\n\n\t<div id=\"col-251048853\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_710072198\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_14-600x800.jpg\" class=\"attachment-large size-large\" alt=\"project of SWIFT lift\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_14-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_14-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_14-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_14-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_14.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_710072198 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3330575546\" class=\"text\">\n\t\t\n<p>From dawn to&#8230;<\/p>\n\t\t\n<style>\n#text-3330575546 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-3330575546 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-251048853 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-251048853 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-572374192\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1178460313\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_02-600x800.jpg\" class=\"attachment-large size-large\" alt=\"free standing lift\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_02-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_02-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_02-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_02-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_02.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1178460313 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2791505196\" class=\"text\">\n\t\t\n<p>dusk.<\/p>\n\t\t\n<style>\n#text-2791505196 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-2791505196 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-572374192 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-572374192 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_775935982 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1035918710\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1177014713\">\n\n\t<div id=\"col-1849177061\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_765779031\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_12-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"Swift lift pro project without pit\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_12-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_12-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_12-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_12-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_12.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_765779031 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1025879466\" class=\"text\">\n\t\t\n<p>The white SWIFT Pro and Oriental White ArtWall perfectly match the light marble stairs and dark wood railings, creating a cohesive and elegant interior.<\/p>\n\t\t\n<style>\n#text-1025879466 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-1025879466 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1849177061 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1849177061 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1035918710 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_970859379\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1807125773\">\n\n\t<div id=\"col-1277228485\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1146388951\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_08-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_08-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_08-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_08-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_08-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_08.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1146388951 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3514397813\" class=\"text\">\n\t\t\n<p>A bird\u2019s-eye view of SWIFT Pro.<\/p>\n\t\t\n<style>\n#text-3514397813 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-3514397813 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1277228485 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1277228485 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_970859379 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1424783496\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1600007364\">\n\n\t<div id=\"col-1043899895\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2078268359\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_07-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_07-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_07-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_07-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_07-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/07\/project_SW107927_07.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2078268359 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-928900430\" class=\"text\">\n\t\t\n<p>SWIFT Pro not only takes you from floor A to B but also serves as a source of light \u2014 day and night.<\/p>\n\t\t\n<style>\n#text-928900430 {\n  font-size: 1rem;\n  color: rgb(255, 145, 150);\n}\n#text-928900430 > * {\n  color: rgb(255, 145, 150);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1043899895 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1043899895 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1424783496 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":16797,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-52820","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Projects - Bungalow Taman Naluri Emas - SWIFT - 100% battery driven home lifts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/au\/projects\/projects-bungalow-taman-naluri-emas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - Bungalow Taman Naluri Emas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/au\/projects\/projects-bungalow-taman-naluri-emas\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T04:49:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/projects-bungalow-taman-naluri-emas\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/projects-bungalow-taman-naluri-emas\\\/\",\"name\":\"Projects - Bungalow Taman Naluri Emas - SWIFT - 100% battery driven home lifts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#website\"},\"datePublished\":\"2025-09-22T04:49:05+00:00\",\"dateModified\":\"2025-09-22T04:49:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/projects-bungalow-taman-naluri-emas\\\/#breadcrumb\"},\"inLanguage\":\"en-AU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/projects-bungalow-taman-naluri-emas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/projects-bungalow-taman-naluri-emas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projects &#8211; Bungalow Taman Naluri Emas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-AU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-AU\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Projects - Bungalow Taman Naluri Emas - SWIFT - 100% battery driven home lifts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/au\/projects\/projects-bungalow-taman-naluri-emas\/","og_locale":"en_US","og_type":"article","og_title":"Projects - Bungalow Taman Naluri Emas","og_url":"https:\/\/swiftlifts.com\/au\/projects\/projects-bungalow-taman-naluri-emas\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","article_modified_time":"2025-09-22T04:49:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/au\/projects\/projects-bungalow-taman-naluri-emas\/","url":"https:\/\/swiftlifts.com\/au\/projects\/projects-bungalow-taman-naluri-emas\/","name":"Projects - Bungalow Taman Naluri Emas - SWIFT - 100% battery driven home lifts","isPartOf":{"@id":"https:\/\/swiftlifts.com\/au\/#website"},"datePublished":"2025-09-22T04:49:05+00:00","dateModified":"2025-09-22T04:49:37+00:00","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/au\/projects\/projects-bungalow-taman-naluri-emas\/#breadcrumb"},"inLanguage":"en-AU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/au\/projects\/projects-bungalow-taman-naluri-emas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/au\/projects\/projects-bungalow-taman-naluri-emas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/au\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/swiftlifts.com\/au\/projects\/"},{"@type":"ListItem","position":3,"name":"Projects &#8211; Bungalow Taman Naluri Emas"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/au\/#website","url":"https:\/\/swiftlifts.com\/au\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/au\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/au\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-AU"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/au\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/au\/","logo":{"@type":"ImageObject","inLanguage":"en-AU","@id":"https:\/\/swiftlifts.com\/au\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/au\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/52820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/comments?post=52820"}],"version-history":[{"count":1,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/52820\/revisions"}],"predecessor-version":[{"id":52821,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/52820\/revisions\/52821"}],"up":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/16797"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/media?parent=52820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}