{"id":39427,"date":"2025-01-08T10:23:08","date_gmt":"2025-01-08T10:23:08","guid":{"rendered":"https:\/\/swiftlifts.com\/projects\/projects-robins-townhouse\/"},"modified":"2025-02-05T06:16:30","modified_gmt":"2025-02-05T06:16:30","slug":"projects-robins-townhouse","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/au\/projects\/projects-robins-townhouse\/","title":{"rendered":"Projects &#8211; Robins Townhouse"},"content":{"rendered":"\n\t<section class=\"section why_a_home_lift\" id=\"section_1870086002\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"633\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_hero_SW108260.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\" style=\"max-width:90%\" id=\"row-1197018748\">\n\n\t<div id=\"col-750547011\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2298146072\" class=\"text\">\n\t\t\n<h1>Robins Townhouse<\/h1>\n\t\t\n<style>\n#text-2298146072 {\n  font-size: 2rem;\n  color: rgb(255, 255, 255);\n}\n#text-2298146072 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-750547011 > .col-inner {\n  margin: 200px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1870086002 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #dbe0d1;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_2068059916\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-419271015\">\n\n\t<div id=\"col-130067112\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1526141038\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_07-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_07-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_07-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_07-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_07-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_07.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1526141038 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-130067112 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-130067112 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2079541113\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2721526897\" class=\"text\">\n\t\t\n<h2>Robins Townhouse<\/h2>\n\t\t\n<style>\n#text-2721526897 {\n  font-size: 1rem;\n  color: rgb(30, 98, 122);\n}\n#text-2721526897 > * {\n  color: rgb(30, 98, 122);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-879240787\" class=\"text\">\n\t\t\n<p>In the heart of Pluit, a thriving coastal area on Java\u2019s island in Indonesia, stands a newly completed four-story townhouse that seamlessly blends history and modernity. Java, synonymous with coffee and culture, is where Dutch colonial influences meet a vibrant mix of traditions, religions, and architectural styles. This dynamic spirit is reflected in the home, which takes its design inspiration from Japanese Modern architecture \u2014 a style that balances simplicity, functionality, and harmony with nature. Equipped with a SWIFT Lite home lift, the residence offers smooth, stylish connections between its levels while honoring the island\u2019s heritage of blending the classic with the contemporary.   <\/p>\n<p><b>Model:<\/b> SWIFT Lite <br \/><b>Floors:<\/b> 4 <br \/><b>Lift Size: <\/b>L, Large<b> <br \/>Lift Colour:<\/b> Traffic White <br \/><b>Platform Wall:<\/b> Resin board <br \/><b>Lift Carpet:<\/b> Vinyl Black <br \/><b>Location:<\/b> Pluit, Jakarta, on Indonesian island Java<\/p>\n\t\t\n<style>\n#text-879240787 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-879240787 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-right\"><div class=\"is-divider divider clearfix\" style=\"max-width:100%;background-color:rgb(131, 175, 175);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2079541113 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2079541113 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2068059916 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1306502989\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1861680212\">\n\n\t<div id=\"col-163650312\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1023137321\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_11-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_11-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_11-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_11-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_11-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_11.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1023137321 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2409730998\" class=\"text\">\n\t\t\n<p>Inside the gates of Robins Townhouse, you are greeted by the soothing sound of trickling water from a small pond with lively fish.<\/p>\n\t\t\n<style>\n#text-2409730998 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-2409730998 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-163650312 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-163650312 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-390284303\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1352939158\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_17-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_17-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_17-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_17-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_17-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_17.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1352939158 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1678764498\" class=\"text\">\n\t\t\n<p>One, two, three, four floors. No worries. SWIFT has got you covered.   <\/p>\n\t\t\n<style>\n#text-1678764498 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-1678764498 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-390284303 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-390284303 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1306502989 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1019495777\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1360867211\">\n\n\t<div id=\"col-444768429\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1089717824\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_02-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_02-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_02-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_02-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_02-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_02.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1089717824 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-256676531\" class=\"text\">\n\t\t\n<p>The ground floor features an inviting entrance area and flooring in natural granite. The walls are adorned with wooden paneling, adding warmth and coziness while also softening the acoustics.  <\/p>\n\t\t\n<style>\n#text-256676531 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-256676531 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-444768429 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-444768429 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1019495777 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1554534309\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-129655533\">\n\n\t<div id=\"col-1622472920\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1484710864\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_09-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_09-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_09-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_09-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_09-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_09.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1484710864 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2242266618\" class=\"text\">\n\t\t\n<p>SWIFT Lite and a lot of natural light.<\/p>\n\t\t\n<style>\n#text-2242266618 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-2242266618 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1622472920 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1622472920 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1764874955\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_370861286\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_08-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_08-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_08-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_08-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_08-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_08.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_370861286 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2115131638\" class=\"text\">\n\t\t\n<p>Inspired by Modern Japanese and Japandi &#8211; a blend of Japanese and Scandi(navian) design. <\/p>\n\t\t\n<style>\n#text-2115131638 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-2115131638 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1764874955 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1764874955 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1554534309 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_756108895\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-228694189\">\n\n\t<div id=\"col-838737094\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1812367443\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_16-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_16-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_16-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_16-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_16-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_16.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1812367443 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2567665364\" class=\"text\">\n\t\t\n<p>Minimalism and tranquility. <\/p>\n\t\t\n<style>\n#text-2567665364 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-2567665364 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-838737094 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-838737094 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1037887169\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_20575832\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_14-600x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_14-600x800.jpg 600w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_14-300x400.jpg 300w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_14-768x1024.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_14-1152x1536.jpg 1152w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_portrait_SW108260_14.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_20575832 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3936526308\" class=\"text\">\n\t\t\n<p>Celebrating everyday beauty and a connection with nature.<\/p>\n\t\t\n<style>\n#text-3936526308 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-3936526308 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1037887169 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1037887169 > .col-inner {\n    padding: 0px 30% 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_756108895 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_920649188\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1206579566\">\n\n\t<div id=\"col-170927365\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_381919842\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_04-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_04-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_04-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_04-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_04-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_04.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_381919842 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2186150850\" class=\"text\">\n\t\t\n<p>Japanese Modern interior design rooted in minimalist principles, clean lines, and natural materials are visible in this home. <\/p>\n\t\t\n<style>\n#text-2186150850 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-2186150850 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-170927365 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-170927365 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_920649188 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1217848931\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1777457586\">\n\n\t<div id=\"col-1195102105\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2045044711\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_05-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_05-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_05-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_05-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_05-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_05.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2045044711 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2410445356\" class=\"text\">\n\t\t\n<p>Take the stairs or the SWIFT home lift to reach the other floors. <\/p>\n\t\t\n<style>\n#text-2410445356 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-2410445356 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1195102105 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1195102105 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1217848931 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_165723560\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1477967096\">\n\n\t<div id=\"col-772372849\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_901165426\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_06-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_06-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_06-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_06-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_06-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_06.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_901165426 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2059864087\" class=\"text\">\n\t\t\n<p>Christmas vibes at Robins Townhouse. <\/p>\n\t\t\n<style>\n#text-2059864087 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-2059864087 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-772372849 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-772372849 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_165723560 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1631180756\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1238866519\">\n\n\t<div id=\"col-1393473910\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_804805108\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_18-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_18-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_18-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_18-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_18-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_18.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_804805108 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1036990429\" class=\"text\">\n\t\t\n<p>Living room and a dedicated study behind. <\/p>\n\t\t\n<style>\n#text-1036990429 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-1036990429 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1393473910 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1393473910 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1631180756 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_486365870\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-1965383613\">\n\n\t<div id=\"col-1180537052\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_724223310\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"538\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_01-1400x738.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_01-1400x738.jpg 1400w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_01-759x400.jpg 759w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_01-768x405.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_01-1536x809.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/12\/project_landscape_SW108260_01.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_724223310 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3759450483\" class=\"text\">\n\t\t\n<p>Japanese Modern has a deep appreciation for nature, clearly reflected in the courtyard of Robin&#8217;s Townhouse.<\/p>\n\t\t\n<style>\n#text-3759450483 {\n  font-size: 1rem;\n  color: rgb(131, 175, 175);\n}\n#text-3759450483 > * {\n  color: rgb(131, 175, 175);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1180537052 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1180537052 > .col-inner {\n    padding: 0px 15% 0px 15%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1971104747\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/projects\/\" class=\"button alert lowercase\" >\n\t\t<span>Click here to see more projects<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1971104747 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1971104747 > .col-inner {\n    padding: 0px 0px 0px 30%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1505499345\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"https:\/\/swiftlifts.com\/en\/products\/swift-lite-a-small-house-lift\/\" class=\"button success lowercase\" >\n\t\t<span>SWIFT Lite product page<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1505499345 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1505499345 > .col-inner {\n    padding: 0px 30% 0px 0%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_486365870 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":16797,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-39427","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Projects - Robins Townhouse - SWIFT - 100% battery driven home lifts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/au\/projects\/projects-robins-townhouse\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - Robins Townhouse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/au\/projects\/projects-robins-townhouse\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-05T06:16:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/projects-robins-townhouse\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/projects-robins-townhouse\\\/\",\"name\":\"Projects - Robins Townhouse - SWIFT - 100% battery driven home lifts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#website\"},\"datePublished\":\"2025-01-08T10:23:08+00:00\",\"dateModified\":\"2025-02-05T06:16:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/projects-robins-townhouse\\\/#breadcrumb\"},\"inLanguage\":\"en-AU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/projects-robins-townhouse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/projects-robins-townhouse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Projects &#8211; Robins Townhouse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-AU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-AU\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Projects - Robins Townhouse - SWIFT - 100% battery driven home lifts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/au\/projects\/projects-robins-townhouse\/","og_locale":"en_US","og_type":"article","og_title":"Projects - Robins Townhouse","og_url":"https:\/\/swiftlifts.com\/au\/projects\/projects-robins-townhouse\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","article_modified_time":"2025-02-05T06:16:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/au\/projects\/projects-robins-townhouse\/","url":"https:\/\/swiftlifts.com\/au\/projects\/projects-robins-townhouse\/","name":"Projects - Robins Townhouse - SWIFT - 100% battery driven home lifts","isPartOf":{"@id":"https:\/\/swiftlifts.com\/au\/#website"},"datePublished":"2025-01-08T10:23:08+00:00","dateModified":"2025-02-05T06:16:30+00:00","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/au\/projects\/projects-robins-townhouse\/#breadcrumb"},"inLanguage":"en-AU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/au\/projects\/projects-robins-townhouse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/au\/projects\/projects-robins-townhouse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/au\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/swiftlifts.com\/au\/projects\/"},{"@type":"ListItem","position":3,"name":"Projects &#8211; Robins Townhouse"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/au\/#website","url":"https:\/\/swiftlifts.com\/au\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/au\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/au\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-AU"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/au\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/au\/","logo":{"@type":"ImageObject","inLanguage":"en-AU","@id":"https:\/\/swiftlifts.com\/au\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/au\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/39427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/comments?post=39427"}],"version-history":[{"count":1,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/39427\/revisions"}],"predecessor-version":[{"id":42413,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/39427\/revisions\/42413"}],"up":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/16797"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/media?parent=39427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}