{"id":16840,"date":"2022-06-30T14:22:20","date_gmt":"2022-06-30T14:22:20","guid":{"rendered":"https:\/\/swiftlifts.com\/our-story\/"},"modified":"2024-08-29T06:28:13","modified_gmt":"2024-08-29T06:28:13","slug":"our-story","status":"publish","type":"page","link":"https:\/\/swiftlifts.com\/au\/our-story\/","title":{"rendered":"Our story"},"content":{"rendered":"\n\t<section class=\"section design_pioneers_sec has-parallax is-full-height\" id=\"section_1063221459\">\n\t\t<div class=\"section-bg fill\" data-parallax-container=\".section\" data-parallax-background data-parallax=\"-10\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1619\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2022\/06\/SWIFT_Sweden_Stockholm_02_beskuren.jpg\" class=\"bg attachment-original size-original\" alt=\"SWIFT Sweden\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1878905392\">\n\n\t<div id=\"col-793883509\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-1876300651\">\n\n\t<div id=\"col-738228708\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"text-right\"><div class=\"is-divider divider clearfix\" style=\"max-width:52%;background-color:rgb(255, 201, 189);\"><\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-738228708 > .col-inner {\n  padding: 0px 0px 50px 0px;\n  margin: 0px 0px 0px 30px;\n}\n@media (min-width:550px) {\n  #col-738228708 > .col-inner {\n    padding: 0px 0px 50px 0px;\n    margin: 0px 0px 0px 100px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"text-1744014718\" class=\"text\">\n\t\t\n<h1>Swedish quality at its core<\/h1>\n\t\t\n<style>\n#text-1744014718 {\n  font-size: 1.25rem;\n  color: rgb(255, 201, 189);\n}\n#text-1744014718 > * {\n  color: rgb(255, 201, 189);\n}\n@media (min-width:550px) {\n  #text-1744014718 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1808363103\">\n\n\t<div id=\"col-184961646\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:52%;background-color:rgb(255, 201, 189);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1192747218\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3244094813\" class=\"text\">\n\t\t\n<p>SWIFT is a Swedish home tech company founded by home lift pioneers. Joining forces with some of the best home lift distributors in the world, SWIFT has created an international team of dedicated entrepreneurs who all share a passion for products that can make a difference.\u200b<\/p>\n<p>SWIFT was born in Stockholm, Sweden and this is where we have our HQ office.<\/p>\n\t\t\n<style>\n#text-3244094813 {\n  font-size: 1.25rem;\n  line-height: 1.4;\n  text-align: center;\n  color: rgb(255, 201, 189);\n}\n#text-3244094813 > * {\n  color: rgb(255, 201, 189);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1192747218 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1192747218 > .col-inner {\n    margin: 0px 0px 0px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1808363103 > .col > .col-inner {\n  padding: 60px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-793883509 > .col-inner {\n  margin: 0px 0px 0px -30px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1878905392 > .col > .col-inner {\n  padding: 0px 0px 0px 0;\n}\n@media (min-width:550px) {\n  #row-1878905392 > .col > .col-inner {\n    padding: 0px 0px 0px 0;\n  }\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1063221459 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 100vh;\n}\n@media (min-width:550px) {\n  #section_1063221459 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_114016053\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width\"  id=\"row-2069760310\">\n\n\t<div id=\"col-105030546\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe loading=\"lazy\" title=\"SWIFT - New Ways To Move\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/IMOYFPNblLs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-105030546 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-105030546 > .col-inner {\n    padding: 50px 300px 0 300px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_114016053 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(255, 201, 189);\n}\n@media (min-width:550px) {\n  #section_114016053 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section is-full-height\" id=\"section_1832671345\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2000x1000px_2-1.jpg\" class=\"bg attachment- size-\" alt=\"swift our story\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-297796881\">\n\n\t<div id=\"col-1322352274\" class=\"col hide-for-medium medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1605245314\" class=\"col show-for-medium small-4 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-774540473\" class=\"col medium-4 small-8 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1612812975\" class=\"text\">\n\t\t\n<h2>Quality and Manufacturing<\/h2>\n<p>The R&amp;D Centre and factory for assembly of key components is located in Falkenberg on the Swedish west coast.<\/p>\n\t\t\n<style>\n#text-1612812975 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n  color: rgb(0, 0, 0);\n}\n#text-1612812975 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:2px;background-color:rgb(255, 145, 150);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-297796881 > .col > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1832671345 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 100vh;\n  background-color: rgb(219, 224, 209);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1637403997\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2000x1000px_3.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(219, 224, 209);border-width:2px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-874165644\">\n\n\t<div id=\"col-616067577\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3365736427\" class=\"text\">\n\t\t\n<p>In Falkenberg we have our electronic laboratory, and this is where we carry out noise\/vibration- and long term testing.<\/p>\n\t\t\n<style>\n#text-3365736427 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n  color: rgb(255,255,255);\n}\n#text-3365736427 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0.2em;margin-bottom:0.2em;max-width:100%;height:2px;background-color:rgb(219, 224, 209);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-616067577 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-616067577 > .col-inner {\n    padding: 0px 5% 0px 40%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-874165644 > .col > .col-inner {\n  padding: 20% 20% 20% 20%;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1637403997 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_92401927\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-930697490\">\n\n\t<div id=\"col-204860848\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2125274665\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"652\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2560x1280px_4_x-1251x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2560x1280px_4_x-1251x800.jpg 1251w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2560x1280px_4_x-625x400.jpg 625w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2560x1280px_4_x-768x491.jpg 768w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2560x1280px_4_x-1536x983.jpg 1536w, https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2560x1280px_4_x.jpg 2001w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2125274665 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-204860848 > .col-inner {\n  padding: 0px 0 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1265888260\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2095692989\" class=\"text\">\n\t\t\n<p>SWIFT complies with Europe\u2019s strictest lift regulations European Machinery Directive 2006\/42\/EC and harmonized standard EN81-41.<\/p>\n\t\t\n<style>\n#text-2095692989 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0.2em;margin-bottom:0.2em;max-width:100%;height:2px;background-color:rgb(30, 98, 122);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1265888260 > .col-inner {\n  padding: 20px 70px 0px 70px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_92401927 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(255, 201, 189);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_232056361\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2000x1000px_5.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-1643522741\">\n\n\t<div id=\"col-1224313847\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1886458567\" class=\"text\">\n\t\t\n<p>The control system is powered by Thor Engineering \u2122- one of the most powerful lift control systems in the world.<\/p>\n\t\t\n<style>\n#text-1886458567 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n  color: rgb(250, 245, 242);\n}\n#text-1886458567 > * {\n  color: rgb(250, 245, 242);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0.2em;margin-bottom:0.2em;max-width:100%;height:2px;background-color:rgb(250, 245, 242);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1224313847 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1224313847 > .col-inner {\n    padding: 0px 5% 0px 40%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1643522741 > .col > .col-inner {\n  padding: 20% 20% 20% 20%;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_232056361 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1171288685\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1000\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2000x1000px_6-1.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:2px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-2079300613\">\n\n\t<div id=\"col-822154036\" class=\"col hide-for-medium medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-822154036 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-546216359\" class=\"col show-for-medium small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-546216359 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 10% 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1219954862\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3453623411\" class=\"text\">\n\t\t\n<p>The Thor system has been developed by the Swedish SafeLine Group and has been uniquely tailored to meet the needs of the SWIFT home lift.<\/p>\n\t\t\n<style>\n#text-3453623411 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n  color: rgb(250, 245, 242);\n}\n#text-3453623411 > * {\n  color: rgb(250, 245, 242);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0.2em;margin-bottom:0.2em;max-width:100%;height:2px;background-color:rgb(31, 173, 183);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1219954862 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1219954862 > .col-inner {\n    padding: 0px 5% 0px 40%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-2079300613 > .col > .col-inner {\n  padding: 30% 20% 0% 20%;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1171288685 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1961536899\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1280\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2560x1280px_7-1.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(31, 173, 183);border-width:2px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-1890991076\">\n\n\t<div id=\"col-539390998\" class=\"col show-for-medium medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-539390998 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1737908665\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2961918285\" class=\"text\">\n\t\t\n<p>All critical components such as control system and drive unit are designed and manufactured in Sweden and Germany. The rest of the suppliers come from Europe and Asia and they have all been carefully selected after extensive testing and reviewing.<\/p>\n\t\t\n<style>\n#text-2961918285 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n  color: rgb(255,255,255);\n}\n#text-2961918285 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0.2em;margin-bottom:0.2em;max-width:100%;height:2px;background-color:rgb(255, 201, 189);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1737908665 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1737908665 > .col-inner {\n    padding: 0px 5% 0px 40%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1500215059\" class=\"col hide-for-medium medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1500215059 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1890991076 > .col > .col-inner {\n  padding: 30% 20% 10% 20%;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1961536899 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1662795631\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1280\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2560x1280px_8.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(255, 201, 189);border-width:2px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-center\"  id=\"row-1746300647\">\n\n\t<div id=\"col-1970950744\" class=\"col show-for-medium small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1970950744 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-745320431\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner text-left\" style=\"background-color:rgb(255, 201, 189);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1086762714\" class=\"text\">\n\t\t\n<h2>Manufacturing<\/h2>\n<p>The SWIFT assembly factory is one of the most advanced home lift factories in the world.<\/p>\n\t\t\n<style>\n#text-1086762714 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n  color: rgb(0, 0, 0);\n}\n#text-1086762714 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:2px;background-color:rgb(255, 145, 150);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-745320431 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1147135613\" class=\"col hide-for-medium medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1147135613 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1746300647 > .col > .col-inner {\n  padding: 10% 10% 10% 10%;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1662795631 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 90vh;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1711663568\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1280\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2560x1280px_9.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:2px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-1237602476\">\n\n\t<div id=\"col-1152982923\" class=\"col show-for-medium medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1152982923 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-847938890\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2992537778\" class=\"text\">\n\t\t\n<p>The modern factory is managed by experienced Swedish professionals and combines Swedish quality with the latest Lean Manufacturing philosophies.<\/p>\n\t\t\n<style>\n#text-2992537778 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n  color: rgb(255,255,255);\n}\n#text-2992537778 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0.2em;margin-bottom:0.2em;max-width:100%;height:2px;background-color:rgb(30, 98, 122);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-847938890 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-847938890 > .col-inner {\n    padding: 0px 5% 0px 40%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-422576664\" class=\"col hide-for-medium medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-422576664 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1237602476 > .col > .col-inner {\n  padding: 30% 20% 30% 20%;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1711663568 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_2025148778\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1280\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_our_story_2560x1280px_10-2.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:2px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-middle\"  id=\"row-1174754790\">\n\n\t<div id=\"col-1438263062\" class=\"col show-for-medium medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1438263062 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1734968421\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2230674525\" class=\"text\">\n\t\t\n<p>In the factory visitors are able to see glimpses of the entire manufacturing process.<\/p>\n\t\t\n<style>\n#text-2230674525 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n  color: rgb(255,255,255);\n}\n#text-2230674525 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0.2em;margin-bottom:0.2em;max-width:100%;height:2px;background-color:rgb(255, 145, 150);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1734968421 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1734968421 > .col-inner {\n    padding: 0px 5% 0px 40%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1268089556\" class=\"col hide-for-medium medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1268089556 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1174754790 > .col > .col-inner {\n  padding: 30% 20% 30% 20%;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2025148778 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_722694923\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t<div class=\"video-overlay no-click fill visible\"><\/div>\n\t<video class=\"video-bg fill visible\" preload playsinline autoplay muted loop>\n\t\t<source src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/swift_taicang_studio3.mp4\" type=\"video\/mp4\">\t<\/video>\n\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:2px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-center\"  id=\"row-2088212618\">\n\n\t<div id=\"col-1838072250\" class=\"col show-for-medium medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1838072250 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-516902462\" class=\"col hide-for-medium medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-516902462 > .col-inner {\n  padding: 0 0px 0px 0px;\n  margin: 0px 0px 0 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-86250062\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3377930250\" class=\"text\">\n\t\t\n<p>Experience the SWIFT Showroom \u2013 a studio built to showcase all aspects of buying and owning a home lift.<\/p>\n\t\t\n<style>\n#text-3377930250 {\n  font-size: 1.25rem;\n  line-height: 1.5;\n  color: #ff9196;\n}\n#text-3377930250 > * {\n  color: #ff9196;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:0.2em;margin-bottom:0.2em;max-width:100%;height:2px;background-color:rgb(255, 145, 150);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-86250062 > .col-inner {\n  padding: 50px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-2088212618 > .col > .col-inner {\n  padding: 1% 0px 30% 0px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_722694923 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  margin-bottom: 0px;\n  min-height: 44vh;\n}\n@media (min-width:550px) {\n  #section_722694923 {\n    min-height: 80vh;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_966050596\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1692\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/SWIFT_Sweden_Falkenberg_Sustainability_2560-3.jpg\" class=\"bg attachment- size-\" alt=\"SWIFT Sweden\" \/>\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(219, 224, 209);border-width:2px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-full-width align-bottom\"  id=\"row-1394540924\">\n\n\t<div id=\"col-1622377935\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2043927621\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1927135852\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"734\" height=\"394\" src=\"https:\/\/swiftlifts.com\/wp-content\/uploads\/2024\/02\/Sustainability3-2.png\" class=\"attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1927135852 {\n  width: 89%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1989865364\" class=\"text\">\n\t\t\n<h1>Swiftly Towards Sustainability<\/h1>\n\t\t\n<style>\n#text-1989865364 {\n  font-size: 1.25rem;\n  text-align: left;\n  color: rgb(255,255,255);\n}\n#text-1989865364 > * {\n  color: rgb(255,255,255);\n}\n@media (min-width:550px) {\n  #text-1989865364 {\n    text-align: left;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2043927621 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-2043927621 > .col-inner {\n    padding: 10% 0px 10% 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-618156663\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3838412053\" class=\"text\">\n\t\t\n<p>SWIFT wants to be part of creating a sustainable society. We believe our home lift can play a small, yet important role in sustainable living and in the way that homes are built in the future.<\/p>\n<p>We have the market\u2019s lowest running costs thanks to our unique drive system (patent pending) and the Tesla-inspired EcoDrive concept, which automatically charges the batteries as the lift moves downwards.<\/p>\n<p>The carpets are made with ECONYL\u00a9, microfibers from nylon waste and recycled plastic bottles from the ocean. 95% of all components in the lift are recyclable.<\/p>\n<p>Join us on the journey towards sustainable, avantgarde home technology.<\/p>\n\t\t\n<style>\n#text-3838412053 {\n  font-size: 1.25rem;\n  text-align: left;\n  color: rgb(255,255,255);\n}\n#text-3838412053 > * {\n  color: rgb(255,255,255);\n}\n@media (min-width:550px) {\n  #text-3838412053 {\n    text-align: left;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-618156663 > .col-inner {\n  padding: 0px 10% 10% 0px;\n}\n@media (min-width:550px) {\n  #col-618156663 > .col-inner {\n    padding: 10% 10% 10% 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1394540924 > .col > .col-inner {\n  border-radius: 83px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_966050596 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-16840","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SWIFT Lifts Story: Swedish Quality in Home Lift Technology<\/title>\n<meta name=\"description\" content=\"Learn about SWIFT Lifts&#039; journey, mission, and dedication to innovation in the lifting industry. See how we have evolved to meet your lifting needs with excellence.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swiftlifts.com\/au\/our-story\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our story\" \/>\n<meta property=\"og:description\" content=\"Learn about SWIFT Lifts&#039; journey, mission, and dedication to innovation in the lifting industry. See how we have evolved to meet your lifting needs with excellence.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swiftlifts.com\/au\/our-story\/\" \/>\n<meta property=\"og:site_name\" content=\"SWIFT - 100% battery driven home lifts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swifthomelifts\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T06:28:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/our-story\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/our-story\\\/\",\"name\":\"SWIFT Lifts Story: Swedish Quality in Home Lift Technology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#website\"},\"datePublished\":\"2022-06-30T14:22:20+00:00\",\"dateModified\":\"2024-08-29T06:28:13+00:00\",\"description\":\"Learn about SWIFT Lifts' journey, mission, and dedication to innovation in the lifting industry. See how we have evolved to meet your lifting needs with excellence.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/our-story\\\/#breadcrumb\"},\"inLanguage\":\"en-AU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swiftlifts.com\\\/au\\\/our-story\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/our-story\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our story\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#website\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/\",\"name\":\"SWIFT - 100% battery driven home lifts\",\"description\":\"NEW WAYS TO MOVE\",\"publisher\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-AU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#organization\",\"name\":\"SWIFT Home Lifts\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-AU\",\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"contentUrl\":\"https:\\\/\\\/swiftlifts.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-SWIFT-Logo-Google.jpg\",\"width\":512,\"height\":512,\"caption\":\"SWIFT Home Lifts\"},\"image\":{\"@id\":\"https:\\\/\\\/swiftlifts.com\\\/au\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swifthomelifts\",\"https:\\\/\\\/www.instagram.com\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.pinterest.se\\\/swifthomelifts\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@swift5669\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SWIFT Lifts Story: Swedish Quality in Home Lift Technology","description":"Learn about SWIFT Lifts' journey, mission, and dedication to innovation in the lifting industry. See how we have evolved to meet your lifting needs with excellence.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swiftlifts.com\/au\/our-story\/","og_locale":"en_US","og_type":"article","og_title":"Our story","og_description":"Learn about SWIFT Lifts' journey, mission, and dedication to innovation in the lifting industry. See how we have evolved to meet your lifting needs with excellence.","og_url":"https:\/\/swiftlifts.com\/au\/our-story\/","og_site_name":"SWIFT - 100% battery driven home lifts","article_publisher":"https:\/\/www.facebook.com\/swifthomelifts","article_modified_time":"2024-08-29T06:28:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swiftlifts.com\/au\/our-story\/","url":"https:\/\/swiftlifts.com\/au\/our-story\/","name":"SWIFT Lifts Story: Swedish Quality in Home Lift Technology","isPartOf":{"@id":"https:\/\/swiftlifts.com\/au\/#website"},"datePublished":"2022-06-30T14:22:20+00:00","dateModified":"2024-08-29T06:28:13+00:00","description":"Learn about SWIFT Lifts' journey, mission, and dedication to innovation in the lifting industry. See how we have evolved to meet your lifting needs with excellence.","breadcrumb":{"@id":"https:\/\/swiftlifts.com\/au\/our-story\/#breadcrumb"},"inLanguage":"en-AU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swiftlifts.com\/au\/our-story\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swiftlifts.com\/au\/our-story\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/swiftlifts.com\/au\/"},{"@type":"ListItem","position":2,"name":"Our story"}]},{"@type":"WebSite","@id":"https:\/\/swiftlifts.com\/au\/#website","url":"https:\/\/swiftlifts.com\/au\/","name":"SWIFT - 100% battery driven home lifts","description":"NEW WAYS TO MOVE","publisher":{"@id":"https:\/\/swiftlifts.com\/au\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swiftlifts.com\/au\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-AU"},{"@type":"Organization","@id":"https:\/\/swiftlifts.com\/au\/#organization","name":"SWIFT Home Lifts","url":"https:\/\/swiftlifts.com\/au\/","logo":{"@type":"ImageObject","inLanguage":"en-AU","@id":"https:\/\/swiftlifts.com\/au\/#\/schema\/logo\/image\/","url":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","contentUrl":"https:\/\/swiftlifts.com\/wp-content\/uploads\/2025\/03\/cropped-SWIFT-Logo-Google.jpg","width":512,"height":512,"caption":"SWIFT Home Lifts"},"image":{"@id":"https:\/\/swiftlifts.com\/au\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/swifthomelifts","https:\/\/www.instagram.com\/swifthomelifts\/","https:\/\/www.linkedin.com\/company\/swifthomelifts\/","https:\/\/www.pinterest.se\/swifthomelifts\/","https:\/\/www.youtube.com\/@swift5669"]}]}},"_links":{"self":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/16840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/comments?post=16840"}],"version-history":[{"count":108,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/16840\/revisions"}],"predecessor-version":[{"id":26318,"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/pages\/16840\/revisions\/26318"}],"wp:attachment":[{"href":"https:\/\/swiftlifts.com\/au\/wp-json\/wp\/v2\/media?parent=16840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}